{"id":95606,"date":"2018-07-12T16:30:56","date_gmt":"2018-07-12T14:30:56","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/ettaruzzo-canta-con-noi-due-giorni-per-ricordare-il-giovane-ultras-scomparso-programma\/"},"modified":"2023-01-16T18:56:16","modified_gmt":"2023-01-16T17:56:16","slug":"227273-ettaruzzo-canta-con-noi-due-giorni-per-ricordare-il-giovane-ultras-scomparso-programma","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/227273-ettaruzzo-canta-con-noi-due-giorni-per-ricordare-il-giovane-ultras-scomparso-programma\/","title":{"rendered":"&#8216;Ettaruzzo canta con noi&#8217;, due giorni per ricordare il giovane ultr\u00e0 scomparso (PROGRAMMA)"},"content":{"rendered":"<h4>Tutto pronto per la nona edizione del \u201cMemorial Ettore Covello\u201d che si svolger\u00e0 sabato 14 luglio presso il Parco Achille Federico di Andreotta. Attesi tifosi di Genoa, Ancona, Casarano, Casertana e Venezia<\/h4>\n<p><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p>COSENZA \u2013 Gli anni passano, ma in tutti i tifosi del Cosenza rimane sempre vivo il ricordo di Ettore Covello, tra le figure pi\u00f9 autorevoli del movimento ultras cosentino che sabato verr\u00e0 ricordato nel tradizionale memorial a lui dedicato a 9 anni dalla sua scomparsa. Ettore Covello, semplicemente \u201cEttaruzzo\u201d, l\u2019indimenticato ultras della Curva Sud allegro, combattivo\u2026 ribelle. <strong>Ha dedicato tutto il suo percorso al fenomeno degli ultr\u00e0, compresa la sua tesi di Laurea \u201dAnalisi sociologica del fenomeno degli ultras\u201c.<\/strong> Come ogni anno la sua famiglia (con i genitori Ondina e Enzo), compagni, amici, conoscenti e ultras lo ricordano dedicandogli una giornata all\u2019insegna dell\u2019aggregazione e dello sport. E quest\u2019anno ci sar\u00e0 un motivo in pi\u00f9 per ricordalo insieme agli Ultr\u00e0 Cosenza 1978 Curva Sud, visto il dibattito &#8220;L&#8217;influenza ultr\u00e0 nel contesto sociale urbano&#8221; che rappresenta il modo di vivere la curva che accomunano quelli che erano e resteranno per sempre gli ideali di \u201cEttaruzzo\u201d. Lo stabile di Via Milelli, alle porte del centro storico, recuperato dal degrado e dall\u2019abbandono dai quei giovani che vivono la Curva e che lo hanno restituito alla citt\u00e0 ridandogli colore e vita. Saranno presenti ultras di Genoa, Ancona, Casarano, Casertana, Venezia, Pordenone e Lanciano.<\/p>\n<p>&nbsp;<\/p>\n<p>Questo il <strong>programma completo della nona edizione del memorial Ettore Covello che avr\u00e0 inizio alle 11.00 di sabato 14 luglio<\/strong>, dove \u00e8 previsto il saluto ai fratelli gemellati e agli amici che ci hanno raggiunto per passare con noi queste due giornate a seguire ci sar\u00e0 un cocktail di benvenuto ed una coreografia in ricordo del nostro amico. Alle 15:00 prender\u00e0 vita il dibattito dal tema \u201cL&#8217;influenza ultr\u00e0 nel contesto sociale urbano\u201d. Un argomento che rappresenta quella che \u00e8 stata la linea guida caratterizzante dell&#8217;attivit\u00e0 ultras del trascorso anno sportivo. Quello che si \u00e8 cercato di fare, restituendo uno stabile abbandonato alla citt\u00e0 ed ai cittadini, \u00e8 affermare, o riaffermare, la presenza sul territorio e la vicinanza ai quartieri e ad i loro abitanti. Alle 16.00 avr\u00e0 inizio il torneo di beach soccer con premiazione finale prevista intorno alle 20.00. La serata proseguir\u00e0 con una cena\/grigliata all\u2019interno del cortile, fuochi e, a seguire ci sar\u00e0 un concerto e dalla mezzanotte il dj set. Domenica mattina invece ritrovo alle 11.00 per la colazione e saluto a chi deve ripartire. Gli altri\u2026 tutti al mare a Diamante. L&#8217;intera citt\u00e0 ed il popolo rossoblu sono invitati a partecipare a quelli che come sempre saranno due giorni indimenticabili nel ricordo del nostro fratello. &#8220;Ettore \u00e8 qua\u2026canta con gli Ultr\u00e0&#8221;.<\/p>\n<p>&nbsp;<\/p>\n<h3 style=\"text-align: right;\">FOTOREPORTER MARCO BELMONTE<\/h3>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-227299\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2018\/07\/13600029_10208220199195597_4649990324137028603_n-1-420x280.jpg\" alt=\"\" width=\"513\" height=\"342\" title=\"\"> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-227300\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2018\/07\/1505639_10200412462632891_1480445708_n-421x280.jpg\" alt=\"\" width=\"515\" height=\"343\" title=\"\"> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-227301\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2018\/07\/11707617_10203133075166977_3309826387602624300_n-440x174.jpg\" alt=\"\" width=\"536\" height=\"212\" title=\"\"> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-227302\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2018\/07\/IMG_9929-420x280.jpg\" alt=\"\" width=\"510\" height=\"340\" title=\"\"><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-227303\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2018\/07\/10403139_169860513395043_3887407443411191363_n-247x280.jpg\" alt=\"\" width=\"479\" height=\"544\" title=\"\">\u00a0<img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-227304\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2018\/07\/36239662_1925533674409789_7157525022683168768_n-269x280.jpg\" alt=\"\" width=\"522\" height=\"544\" title=\"\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tutto pronto per la nona edizione del \u201cMemorial Ettore Covello\u201d che si svolger\u00e0 sabato 14 luglio presso il Parco Achille Federico di Andreotta. Attesi tifosi di Genoa, Ancona, Casarano, Casertana e Venezia<\/p>\n","protected":false},"author":22,"featured_media":95607,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[565,20],"tags":[],"class_list":["post-95606","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-castrolibero-montalto","category-sport"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/95606","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=95606"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/95606\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/95607"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=95606"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=95606"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=95606"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}