{"id":9583,"date":"2012-12-13T12:11:57","date_gmt":"2012-12-13T11:11:57","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=9583"},"modified":"2023-01-17T13:42:44","modified_gmt":"2023-01-17T12:42:44","slug":"4248-al-museo-del-rock-un-incontro-interamente-dedicato-a-lucio-battisti","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/4248-al-museo-del-rock-un-incontro-interamente-dedicato-a-lucio-battisti\/","title":{"rendered":"Al Museo del Rock un incontro interamente dedicato a Lucio Battisti"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>CATANZARO<\/strong> &#8211; Quale musicista ha rappresentato maggiormente le emozioni di tante generazioni di italiani? La risposta arriva dal Museo del Rock venerd\u00ec 14<\/p>\n<p>  <!--more-->  <\/p>\n<p style=\"text-align: justify;\">dicembre per un incontro interamente dedicato a Lucio Battisti, per rivivere la sua straordinaria storia musicale e raccontare il percorso di una carriera vissuta tra tanti diversi generi, dalle prime influenze del beat inglese e dei folk singer americani, alle sperimentazioni rock e progressive, attraversando i sentieri del soul e del rhythm\u2019n\u2019blues fino alla pi\u00f9 innovativa avanguardia. Dopo due importanti incontri della passata edizione dedicati alla musica italiana per la prima volta il tema della serata di \u201cSuoni &amp; Visioni\u201d interesser\u00e0 in esclusiva un singolo artista nazionale, anche se Piergiorgio Caruso e Rino Amato, ai quali \u00e8 affidato il racconto, nell\u2019ascolto del sempre presente vinile d\u2019epoca presenteranno anche artisti stranieri che hanno interpretato le musiche del grande Battisti. Sar\u00e0 l\u2019occasione per discutere della scena musicale italiana nei decenni d\u2019attivit\u00e0 del musicista di Poggio Bustone, comprendere quanto Battisti abbia influenzato quella scena e quanto sia stato importante per la rapida evoluzione musicale in Italia tra gli anni sessanta e settanta. Si parler\u00e0 del rapporto con Giulio Rapetti, in arte Mogol, ma anche del periodo Panella, cos\u00ec come dei gruppi che hanno raggiunto importanti successi grazie alla vena compositiva dell\u2019autore di alcune delle canzoni pi\u00f9 importanti nella tradizione musicale nazionale. Ammette Caruso: \u201cNon sar\u00e0 facile presentare una selezione musicale che accontenti tutti, essendo troppo vasta la produzione di Battisti, quindi cercheremo di mettere in risalto le grandi qualit\u00e0 del musicista.\u201d Un Lucio Battisti raccontato nella sua capacit\u00e0 innovativa, tra rarit\u00e0 e curiosit\u00e0 in grado di tenere alto l\u2019interesse del pubblico di \u201cSuoni &amp; Visioni\u201d, un pubblico eterogeneo e composto da un numero in crescita di appassionati della musica di tutte le et\u00e0. La solita grande attenzione alle cover e pur se la maggiore attenzione sar\u00e0 offerta agli aspetti rock del musicista Battisti, non potranno mancare i riferimenti a quegli interpreti della melodia nazionale, da Mina, a Patty Pravo, a Bruno Lauzi, che hanno reso celebri le composizioni dello stesso Battisti. Gli organizzatori hanno confermato che la serata, curata per gli aspetti tecnici da Giampiero Ferro e per i servizi da Alchimia, sar\u00e0 ricca di sorprese: appuntamento alle 18.30 di venerd\u00ec al Museo del Rock.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>CATANZARO &#8211; Quale musicista ha rappresentato maggiormente le emozioni di tante generazioni di italiani? La risposta arriva dal Museo del Rock venerd\u00ec 14<\/p>\n","protected":false},"author":22,"featured_media":9584,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,17],"tags":[],"class_list":["post-9583","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/9583","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=9583"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/9583\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/9584"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=9583"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=9583"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=9583"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}