{"id":96056,"date":"2018-07-22T06:34:40","date_gmt":"2018-07-22T04:34:40","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/la-capacita-di-reagire-alle-avversita\/"},"modified":"2023-01-16T18:56:47","modified_gmt":"2023-01-16T17:56:47","slug":"228933-la-capacita-di-reagire-alle-avversita","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/228933-la-capacita-di-reagire-alle-avversita\/","title":{"rendered":"La capacit\u00e0 di reagire alle avversit\u00e0"},"content":{"rendered":"<h4>Quando ci troviamo in una situazione drammatica essa ci appare in modo completamente diverso rispetto a come possiamo vederla da semplici spettatori, o rispetto a quando, pur avendola vissuta in prima persona, la ripercorriamo con la mente, a distanza di molto tempo.<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>Questa considerazione che pu\u00f2 sembrare ovvia, non lo \u00e8 poi tanto se consideriamo che ci\u00f2 che avviene in questi casi \u00e8 il contrario di quello che ci si potrebbe aspettare. Una situazione di sofferenza estrema riesce a risultare, paradossalmente, nella maggior parte dei casi, pi\u00f9 comprensibile, pi\u00f9 tollerabile e pi\u00f9 gestibile da parte della persona interessata che da parte di uno spettatore, ovviamente dotato di particolare sensibilit\u00e0 ed altruismo, che <strong>prova ad immedesimarsi in essa. <\/strong><\/p>\n<p>In uno spettatore di questo tipo si determina una sensazione che \u00e8 un misto di tristezza, di rabbia e di impotenza, accompagnata dall\u2019 idea che una condizione simile sarebbe per lui impossibile da sostenere, o sicuramente molto di meno di quanto sembra riuscire a fare la persona che ci si trova dentro. Questa diversa percezione trova la sua spiegazione in quello che sembra accadere spesso, ma non sempre purtroppo, nella realt\u00e0, e cio\u00e8 che nella persona colpita da una grave avversit\u00e0, come pu\u00f2 essere una guerra o una seria malattia, o un lutto, nella maggior parte dei casi, viene fuori una notevole capacit\u00e0 di sopportare, di resistere e soprattutto di reagire, la cosiddetta resilienza, che consente di trovare le risorse psicologiche per reagire in maniera positiva, ad eventi traumatici (il termine \u00e8 stato introdotto da<strong> Boris Cyrulnik<\/strong> in uno studio su bambini sottoposti a traumi violentissimi).<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-228934 alignleft\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2018\/07\/catena-spezzata.jpg\" alt=\"\" width=\"335\" height=\"222\" title=\"\">La messa in campo di questo tipo di risorsa per affrontare un evento negativo avviene, molto verosimilmente, anche per l\u2019acquisizione della consapevolezza di non avere alternative e di dover necessariamente fare i conti con esso, di doverci convivere, cercando di trarne qualche momento di conforto, sapendo di avere nella speranza l\u2019unico punto di appoggio.<\/p>\n<p>Quando vedo in quei territori martoriati da guerre e da attentati, persone che, nonostante quelle tristi condizioni, quella<strong> sofferenza sovraumana,<\/strong> ed il rischio costante di morire, riescono ad accennare ancora un sorriso, sebbene con lo sguardo pieno di tristezza, mi viene da pensare che davvero la sola cosa che possa sorreggerle debba essere la speranza che quella condizione possa cambiare prima o poi. Capisco che se quelle stesse persone potessero come d\u2019incanto vedere cosa c\u2019\u00e8 al di l\u00e0 del loro mondo, e da questo nuovo punto di osservazione (cio\u00e8 dal nostro) potessero guardare le immagini della loro condizione o quella dei loro familiari, la loro angoscia sarebbe ancora pi\u00f9 grande, e verrebbero sopraffatti da essa. L\u2019idea di dover tornare in quei luoghi e di dover riprendere la vita di prima forse li priverebbe di quella forza d\u2019animo che li ha sorrette fino ad allora.<\/p>\n<p>Qualcosa di simile avviene quando ci si imbatte in una<strong> grave malattia.<\/strong> In questi casi, dopo i primi momenti di smarrimento e di sfiducia totale e di depressione, si prova ad affrontare quella situazione con una forza d\u2019animo, spesso fuori dal comune. Tale capacit\u00e0 di reagire, come dicevo, riesce quasi incomprensibile a coloro che osservano dall\u2019esterno, e fa sorgere loro il dubbio che, trovandosi nella stessa situazione, difficilmente saprebbero reagire nello stesso modo. Ma, gi\u00e0 il constatare che una tale reazione avviene molto spesso, pu\u00f2 sortire qualcosa di buono: lasciare la speranza che se colpiti dalla sfortuna si possa avere almeno la fortuna di possedere, e quindi di metterla in campo, questa capacit\u00e0 di reagire positivamente alle avversit\u00e0.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Quando ci troviamo in una situazione drammatica essa ci appare in modo completamente diverso rispetto a come possiamo vederla da semplici spettatori, o rispetto a quando, pur avendola vissuta in prima persona, la ripercorriamo con la mente, a distanza di molto tempo.<\/p>\n","protected":false},"author":31,"featured_media":96057,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[40],"tags":[],"class_list":["post-96056","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura-spettacolo"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/96056","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/31"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=96056"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/96056\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/96057"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=96056"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=96056"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=96056"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}