{"id":96082,"date":"2018-07-22T10:04:05","date_gmt":"2018-07-22T08:04:05","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/spiedini-estivi-per-un-pasto-leggero-e-colorato\/"},"modified":"2023-01-16T18:56:49","modified_gmt":"2023-01-16T17:56:49","slug":"228998-spiedini-estivi-per-un-pasto-leggero-e-colorato","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/228998-spiedini-estivi-per-un-pasto-leggero-e-colorato\/","title":{"rendered":"Spiedini estivi per un pasto leggero e colorato"},"content":{"rendered":"<h4>Ricetta originale e gustosa ideale per &#8216;rinfrescare&#8217; i palati<\/h4>\n<p><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p>Questa settimana voglio prepararvi una ricetta molto particolare: spiedini di frutta con il formaggio. Una prelibatezza a base di\u00a0<strong>melone e formaggio primo sale di capra<\/strong> che coniuga dolce e salato per un sapore esplosivo e &#8216;rinfrescante&#8217;.<\/p>\n<p>&nbsp;<\/p>\n<h3>INGREDIENTI PER 8 PERSONE:<\/h3>\n<p>&nbsp;<\/p>\n<p>8 fettine di melone<br \/>\n4 fettine di formaggio di capra primosale<br \/>\n10 cl olio d&#8217;oliva<br \/>\n16 foglioline di menta<br \/>\norigano quanto basta<br \/>\nsale e pepe quanto basta<\/p>\n<p>Iniziamo tagliando il melone a cubetti di media grandezza, poi tagliamo il formaggio di capra sempre a cubetti possibilmente di dimensioni simili. <strong>Mettiamo tutto in una ciotola e condiamo con l&#8217;olio di oliva, l&#8217;origano, il sale e il pepe.<\/strong> Mescoliamo il tutto per bene. Prendiamo gli spiedini e infilziamo prima il melone, poi il formaggio, la fogliolina di menta e poi di nuovo il melone, il formaggio e la fogliolina di menta, formaggio e chiudiamo con il melone. Facciamo la stessa operazione per tutti gli spiedini. Riponiamoli su un piatto di portata con un filo d&#8217;olio e serviamoli a tavola.<\/p>\n<p>&nbsp;<\/p>\n<p>ABBINAMENTO: ideale con questo piatto un bianco frizzante servito molto freddo.<\/p>\n<p>&nbsp;<\/p>\n<h2 style=\"text-align: center;\">CLICCA IN BASSO PER<\/h2>\n<h2 style=\"text-align: center;\"><\/h2>\n<h2 style=\"text-align: center;\"><a href=\"https:\/\/quicosenza.it\/news\/2241\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #0000ff;\">TUTTE LE RICETTE DELLO CHEF PIERO CANTORE<\/span><\/a><\/h2>\n","protected":false},"excerpt":{"rendered":"<p>Ricetta originale e gustosa ideale per &#8216;rinfrescare&#8217; i palati<\/p>\n","protected":false},"author":22,"featured_media":96083,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[63],"tags":[],"class_list":["post-96082","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gusto"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/96082","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=96082"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/96082\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/96083"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=96082"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=96082"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=96082"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}