{"id":96090,"date":"2018-07-23T09:38:09","date_gmt":"2018-07-23T07:38:09","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/difendersi-dagli-abusi-delle-banche-si-puo-il-libro-di-mario-bortoletto-audio\/"},"modified":"2023-01-16T18:56:49","modified_gmt":"2023-01-16T17:56:49","slug":"229031-difendersi-dagli-abusi-delle-banche-si-puo-il-libro-di-mario-bortoletto-audio","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/229031-difendersi-dagli-abusi-delle-banche-si-puo-il-libro-di-mario-bortoletto-audio\/","title":{"rendered":"Difendersi dagli abusi delle banche? Si pu\u00f2. Il libro di Mario Bortoletto (AUDIO)"},"content":{"rendered":"<h4>Quella di Mario Bortoletto \u00e8 una battaglia vinta, anzi sono tre. Da qui \u00e8 nata l&#8217;idea e la voglia di trasmettere la sua esperienza affinch\u00e8 gli utenti, le persone, le aziende, non si lascino abbindolare da alcuni istituti di credito.\u00a0<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>PADOVA &#8211; <strong>Mario Bortoletto \u00e8 un imprenditore edile<\/strong> <strong>padovano<\/strong> che ha aperto un vero e proprio mondo parallelo intorno ai rapporti con le banche, quando si \u00e8 imbattuto in una storia molto comune in Italia: un direttore di banca che era arrivato a chiamarlo tutti i giorni perch\u00e8, secondo lui, doveva rientrare di un debito di 22mila euro. Ed invece \u00e8 passato da debitore a creditore, facendo emergere come queli conti delle banche fossero sbagliati. Ed \u00e8 riuscito per ben quattro volte a passare da debitore a creditore di diversi colossi bancari nazionali.<\/p>\n<p><strong>In Italia, da Nord a Sud, milioni di persone hanno problemi con le banche,<\/strong> cosiddette sofferenze, cio\u00e8 soldi che gli istituti di credito non riescono a recuperare e per questo &#8216;perseguitano&#8217; il cliente fino a farlo soffocare. Ma a volte quella che raccontano le banche, \u00e8 una bugia. Bortoletto, e con lui centinaia di correntisti che hanno seguito i suoi consigli, racconta i <strong>giochi sporchi su conti correnti, prestiti e mutui.<\/strong><\/p>\n<p>Il suo libro si legge tutto d\u2019un fiato, \u00e8 scritto in maniera semplice ed \u00e8 un vero e proprio vademecum con molti esempi, per districarsi nel caos delle regole bancarie, soprattutto quelle &#8216;non scritte&#8217;. Un libro pensato per sostenere persone e imprenditori in difficolt\u00e0 e aiutare a gestire le proprie relazioni con le banche, a stare attenti ai rapporti con gli istituti di credito facendo i propri diritti senza soccombere, anche in quelle situazioni dove non sembra esserci via d&#8217;uscita.<\/p>\n<p>La storia dell&#8217;imprenditore di Vigonza, vuole essere anche una speranza concreta per scongiurare altri nuovi casi, in cui le banche hanno letteralmente &#8216;ucciso&#8217; gli imprenditori; persone che hanno rivolto un&#8217;arma contro se stesse o si sono tolti la vita nelle loro imprese perch\u00e8 si sono sentite stritolate: &#8220;bisogna dire basta agli istituti di credito che ti tolgono tutto quello che hai ottenuto, con tanti sacrifici. Sono giganti di argilla che si possono sconfiggere\u201d. E non ci vuole la magia ma solo la caparbiet\u00e0 di non arrendersi: &#8220;Tutti noi pensiamo di essere debitori nei confronti delle banche, ma in realt\u00e0 siamo creditori. mettiamocelo tutti bene in testa\u201d.<\/p>\n<p>L&#8217;intento del suo libro dunque, \u00e8 quello di divulgare la sua battaglia affinch\u00e8 possa diventare la battaglia di molti altri onesti cittadini italiani, vessati dalle banche e oggi Bortoletto viene contattato da tutto lo stivale, da nord a sud. Ha infatti fondato un<span style=\"color: #0000ff;\"><strong> <a style=\"color: #0000ff;\" href=\"https:\/\/quicosenza.it\/news\/5390\" target=\"_blank\" rel=\"noopener\">Movimento contro l&#8217;usura bancaria<\/a><\/strong><\/span> per assistere le persone che subiscono le pretese spesso infondate delle banche che di certo, non si fanno scrupoli a pignorare, a mettere all&#8217;asta beni essenziali come la casa, l&#8217;azienda o il capannone, frutto magari di una vita di lavoro e sacrifici.<\/p>\n<p>Ai microfoni di <strong>RLB<\/strong> ha raccontato quando \u00e8 nata la sua &#8216;<strong>vocazione<\/strong>&#8216; e soprattutto la vicenda a lui accaduta personalmente che lo ha portato a diventare da &#8216;debitore&#8217; a &#8216;creditore&#8217;<\/p>\n<h4><span style=\"color: #ff0000;\">ASCOLTA L&#8217;INTERVISTA<\/span><br \/>\n[audio_mp3 url=&#8221;https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2018\/07\/bortoletto-libro-banche.mp3&#8243;]<\/h4>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-229044 alignleft\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2018\/07\/bortoletto.jpg\" alt=\"\" width=\"338\" height=\"379\" title=\"\">&#8220;Dieci anni fa avevo un direttore di banca che chiamava in ufficio e in maniera sempre pi\u00f9 minacciosa mi chiedeva la restituzione di 22.500 euro. Spesso le banche lo fanno: chiamano e minacciano e la minaccia principale \u00e8 &#8220;ti segnalo alla centrale rischi (CRIF)&#8221;. Cos\u00ec la persona non pu\u00f2 neanche comprare una bicicletta usata perch\u00e8 risultando cattivo pagatore, nessuno ti fa credito. Mia moglie era preoccupata perch\u00e8 mi vedeva sempre nervoso, non riuscivo pi\u00f9 a vivere sereno, ero molto preoccupato e temevo per la mia impresa edile. Essere segnalati voleva dire che tutti i fornitori, mi avrebbero chiesto i pagamenti anticipati e sarebbe stato impossibile continuare a lavorare. Siccome sono testardo e pignolo ho iniziato a studiare, soprattutto su Internet, e ho capito che <strong>questi<\/strong> <strong>giganti,\u00a0che hanno spesso le gambe d&#8217;argilla, vanno sempre controllati&#8221;.<\/strong><\/p>\n<h3>L&#8217;importanza della perizia econometrica<\/h3>\n<p>&#8220;E cos\u00ec ho fatto la verifica del mio rapporto di conto corrente &#8211; spiega Bortoletto &#8211; che si chiama &#8220;<strong>perizia econometrica<\/strong>&#8220;, dalla quale \u00e8 risultato che<strong> io non avevo debiti con la banca bens\u00ec avevo un credito di 67.500<\/strong> <strong>euro<\/strong>. Quando l&#8217;ho scoperto ero anche un p\u00f2 dubbioso, mi sembrava impossibile. E cos\u00ec ho chiamato io quel &#8216;direttore minaccioso&#8217; e mi sono recato in filiale pronto per &#8220;pagare&#8221;. Sono arrivato l\u00ec e ho chiesto:<strong> &#8220;allora direttore? Quanto le devo?&#8221;.<\/strong> Alla sua risposta (22.500 euro) ho chiesto se mi avessero fatto uno sconto dopo 18 anni che lavoravo con loro. Il direttore mi ha risposto che &#8220;le banche non fanno sconti&#8221;, ma che avrebbero potuto &#8216;<strong>scontarmi&#8217; 100 euro<\/strong>. E cos\u00ec &#8211; racconta Bortoletto &#8211; ho fatto loro un <strong>assegno di 30mila euro.\u00a0 <\/strong>Ovviamente il direttore della banca mi ha chiesto il perch\u00e8 di quella cifra, dato che io avrei dovuto restituire solo 22.500 euro. &#8220;Glielo spiego subito signor direttore &#8211; ho risposto &#8211; perch\u00e8 vuol dire che la vostra banca, dopo 18 anni che lavoro, \u00e8 messa male e io voglio aiutarvi&#8221;. Ovviamente l&#8217;assegno non gliel&#8217;ho dato ma <strong>gli ho consegnato la &#8216;perizia econometrica<\/strong>&#8216; e cos\u00ec <strong>l&#8217;ho visto impallidire<\/strong>. E&#8217; diventato rosso e mi ha detto &#8220;guardi che noi queste cause le vinciamo tutte&#8221;. E cos\u00ec mi sono rivoltao al direttore dicendogli: &#8220;guardi non importa se le vincete tutte, ma sta di fatto che qui ci sono <strong>30mila euro di usura<\/strong>,<strong> sui 67mila che mi dovete dare<\/strong>. Se mi date i 67mila io vi d\u00f2 i 22mila che vi devo&#8221;.<\/p>\n<p>Ne \u00e8 scaturita una breve &#8216;riunione&#8217; con un altro dipendente dell&#8217;istituto bancario e quando sono tornati mi hanno comunicato di avere una bella notizia per me: <strong>&#8220;le diamo noi 5mila euro&#8221;.\u00a0<\/strong>Ed \u00e8 qui che ho risposto: &#8220;scusate ma voi fate lo sconto sui miei soldi?&#8221; ed hanno addirittura alzato la posta, a 10mila&#8230; 17mila..&#8221;.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-229046 alignright\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2018\/07\/da-debitore-a-creditore-bortoletto-.jpg\" alt=\"\" width=\"241\" height=\"315\" title=\"\">A quel punto ho risposto &#8216;no grazie&#8217; e ho detto &#8220;vado in tribunale&#8221;. La banca \u00e8 stata condannata a restituirmi i 67 mila pi\u00f9 settemila pi\u00f9 novemila di interessi&#8221;. Questo mi ha fatto capire quanto sia importante far comprendere alle persone in difficolt\u00e0 ma anche non in difficolt\u00e0 che non ci si deve arrendere all&#8217;arroganza bancaria. La gente non lo sa, ma quante persone hanno perso la casa, lo studio&#8230; Molte volte il debitore non \u00e8 il correntista ma la banca e abbiamo migliaia di sentenze che ci danno ragione. Lo facciamo da anni e abbiamo avuto risultati eccezionali e non dobbiamo avere paura&#8221;.<\/p>\n<p>&#8220;La perizia econometrica serve a questo: non \u00e8 altro che un controllo ai raggi X del rapporto, del costo del denaro effettivo che la banca ci ha applicato perch\u00e8 ci sono tante commissioni e spese che lievitano in maniera subdola. E tu che lavori come (fatemi passare il termine) una bestia, e fai a fine anno i tuoi bilanci preventivi e pensi di aver lavorato bene, quando apri il cassetto per trovare i tuoi soldi, quei soldi li ha qualcun&#8217;altro. Ricordiamoci che le banche sono dei nostri &#8220;fornitori&#8221; &#8211; conclude &#8211; ed \u00e8 giusto che, se ci forniscono denaro glielo ritorniamo. Ma purtroppo il &#8220;giusto&#8221;, per molte banche italiane, \u00e8 molto sul &#8216;vago&#8217;. Perci\u00f2 dobbiamo verificare e capire come siamo trattati&#8221;. Difendersi \u00e8 possibile, cos\u00ec come vincere sull&#8217;arroganza.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Quella di Mario Bortoletto \u00e8 una battaglia vinta, anzi sono tre. Da qui \u00e8 nata l&#8217;idea e la voglia di trasmettere la sua esperienza affinch\u00e8 gli utenti, le persone, le aziende, non si lascino abbindolare da alcuni istituti di credito.\u00a0<\/p>\n","protected":false},"author":22,"featured_media":96091,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[571,25],"tags":[],"class_list":["post-96090","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-in-evidenza","category-libri"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/96090","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=96090"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/96090\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/96091"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=96090"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=96090"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=96090"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}