{"id":9624,"date":"2012-12-13T16:21:41","date_gmt":"2012-12-13T15:21:41","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=9624"},"modified":"2023-01-17T13:42:46","modified_gmt":"2023-01-17T12:42:46","slug":"4269-rende-riapre-il-museo-darte-dellotto-e-novecento","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/4269-rende-riapre-il-museo-darte-dellotto-e-novecento\/","title":{"rendered":"Rende, riapre il Museo d&#8217;Arte dell&#8217;Otto e Novecento"},"content":{"rendered":"<p><span style=\"font-size: 11.818181991577148px; line-height: 18.651514053344727px; text-align: justify; background-color: #ffffff;\"><\/span><\/p>\n<p><strong>RENDE<\/strong> &#8211; Riapre il MAON di Rende ammodernato e tecnologico. Dopo diversi mesi di chiusura durante i quali sono stati realizzati importanti interventi di impiantistica<\/p>\n<p>  <!--more-->  <\/p>\n<p>(climatizzazione, antincendio, illuminotecnica) e di sistemazione interna con nuove collezioni e adeguamenti tecnologici, il Museo d&#8217;Arte dell&#8217;Otto e Novecento, ubicato a palazzo Vitari (sec XVIII) nel Centro Storico, presenter\u00e0 domenica 16 dicembre alle ore 17:30 la sua nuova veste al pubblico, mettendo in mostra alcune delle sue opere pi\u00f9 importanti assieme a nuove acquisizioni. All&#8217;inaugurazione interverranno il sindaco di Rende Vittorio Cavalcanti, il consigliere regionale Sandro Principe, il soprintendente ai Beni Storici Artistici e Etnoantropologici della Calabria Fabio De Chirico e il direttore del MAON Tonino Sicoli.<br \/>I visitatori del MAON troveranno alcune novit\u00e0 legate ad alcuni interventi effettuati nell&#8217;ambito di un progetto di qualificazione e e valorizzazione del Sistema Museale Regionale, cofinanziati con fondi POR Calabria FESR 2007-2013. Si tratta di finanziamenti assegnati dalla Regione Calabria tramite bando pubblico e finalizzati alla valorizzazione dei beni e delle attivit\u00e0 culturali, per aumentare l&#8217;attrattivit\u00e0 territoriale e per potenziare le istituzioni culturali, i luoghi della cultura e sostenere lo sviluppo dell&#8217;arte contemporanea in Calabria. Il cofinanziamento \u00e8 stato sostenuto nella misura del 10% dall&#8217;Amministrazione comunale di Rende, mentre l&#8217;intero progetto \u00e8 stato ideato e gestito dal Centro per l&#8217;arte e la Cultura \u201cA.Capizzano\u201d, che ha in comodato d&#8217;uso Palazzo Vitari, dove nel 2004 ha istituito i MAON. <br \/>In questo modo l&#8217;offerta museale rendese fa un ulteriore salto di qualit\u00e0, con un museo apprezzato non solo per le mostre di rilievo internazionale, che ha organizzato in questi anni (fra tutte Umberto Boccioni, Mimmo Rotella, Giorgio De Chirico, il Futurismo, il Novecento Italiano, il Secondo Novecento) ma, da ora in poi, anche per gli standard catalografici ICCD (Istituto Centrale per il Catalogo e la Documentazione) e per quelli di comunicazione integrata.<br \/>L&#8217;utilizzo, infatti, di una piattaforma informatica, accessibile al pubblico attraverso una rete wi-fi e un sistema di consultazione mediante touche-screen o dispositivi palmari e QR-Code, per quanto gi\u00e0 noti ma poco usati nella comunicazione dei Musei italiani, men che meno in Calabria, rendono il MAON all&#8217;avanguardia per l&#8217;adozione di soluzioni interattive. Verr\u00e0 presentato, inoltre, il nuovo sito internet del museo.<br \/>Anche il sistema di illuminotecnica, versatile e a luce fredda per non danneggiare le opere d&#8217;arte, dota il Museo di un sistema di ultima generazione a controllo elettronico. Per non dire degli ambianti espositivi, che sono stati adeguatamente climatizzati.<br \/>Per l&#8217;occasione verranno presentate in anteprima le opere messe a disposizione dalla Fondazione Carmine Rizzo e dal collezionista Giuseppe Chiarello, che saranno acquisite con un comodato d&#8217;uso. Fra esse fanno spicco un dipinto di Antonio Marasco del 1936 e uno di Enzo Benedetto del 1978, assieme ad opere degli anni Venti di altri autori del Secondo Futurismo.<br \/>Il MAON gode del patrocinio della Soprintendenza BSAE della Calabria ed ha il riconoscimento, fra i Luoghi del Contemporaneo, del Ministero per i Beni e le Attivit\u00e0 Culturali.<\/p>\n<p><span style=\"font-size: 11.818181991577148px; line-height: 18.651514053344727px; text-align: justify; background-color: #ffffff;\"><br \/><\/span><span style=\"font-size: 11.818181991577148px; line-height: 18.651514053344727px; text-align: justify; background-color: #ffffff;\"><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>RENDE &#8211; Riapre il MAON di Rende ammodernato e tecnologico. Dopo diversi mesi di chiusura durante i quali sono stati realizzati importanti interventi di impiantistica<\/p>\n","protected":false},"author":22,"featured_media":9625,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,563,44],"tags":[],"class_list":["post-9624","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-area-urbana","category-rende"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/9624","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=9624"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/9624\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/9625"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=9624"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=9624"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=9624"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}