{"id":96421,"date":"2018-07-30T13:51:54","date_gmt":"2018-07-30T11:51:54","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/il-comune-di-cosenza-diventa-proprietario-di-una-vasta-area-del-quartiere-gergeri\/"},"modified":"2023-01-16T18:57:10","modified_gmt":"2023-01-16T17:57:10","slug":"230379-il-comune-di-cosenza-diventa-proprietario-di-una-vasta-area-del-quartiere-gergeri","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/230379-il-comune-di-cosenza-diventa-proprietario-di-una-vasta-area-del-quartiere-gergeri\/","title":{"rendered":"Il Comune di Cosenza diventa proprietario di una vasta area del quartiere Gergeri"},"content":{"rendered":"<h4>Il trasferimento del complesso immobiliare \u00e8 avvenuto con il federalismo demaniale volto alla riqualificazione delle periferie<\/h4>\n<p><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p>COSENZA &#8211; L&#8217;Agenzia del Demanio ha trasferito al Comune di Cosenza, grazie alla procedure del federalismo demaniale, un complesso immobiliare di circa 31.000 metri quadri. <strong>L&#8217;area si trova in una zona degradata della citt\u00e0, in localit\u00e0 &#8220;Gergeri&#8221;, caratterizzata da situazioni di marginalit\u00e0 economico-sociale e carenza di servizi.<\/strong> Il trasferimento si inserisce in una pi\u00f9 ampia operazione di riqualificazione urbana e riuso del territorio grazie ai lavori di bonifica volti ad avviare la ripresa sociale e urbanistica di questa zona di Cosenza ed a migliorare la qualit\u00e0 di vita dei residenti. In prossimit\u00e0 dell&#8217;area \u00e8 stato gi\u00e0 realizzato il ponte di Calatrava, una delle opere pi\u00f9 importanti costruite nel Meridione d&#8217;Italia, che rappresenta una parte di un grande progetto di recupero dell&#8217;area di Gergeri: tutta l&#8217;area intorno al compendio trasferito \u00e8 infatti interessata da opere di riconversione tra le quali una nuova piazza anfiteatro, il nuovo Museo delle Scienze e il parco fluviale lungo il fiume Crati.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-230510 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2018\/07\/IMG-20180730-WA0033-412x280.jpg\" alt=\"\" width=\"412\" height=\"280\" title=\"\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il trasferimento del complesso immobiliare \u00e8 avvenuto con il federalismo demaniale volto alla riqualificazione delle periferie<\/p>\n","protected":false},"author":22,"featured_media":96422,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[42],"tags":[],"class_list":["post-96421","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cosenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/96421","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=96421"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/96421\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/96422"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=96421"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=96421"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=96421"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}