{"id":9658,"date":"2012-12-14T09:59:08","date_gmt":"2012-12-14T08:59:08","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=9658"},"modified":"2023-01-17T13:42:48","modified_gmt":"2023-01-17T12:42:48","slug":"4287-mostra-fotografica-bambini-anima-del-mondo","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/4287-mostra-fotografica-bambini-anima-del-mondo\/","title":{"rendered":"Mostra Fotografica &#8220;Bambini, Anima del Mondo&#8221;"},"content":{"rendered":"<p><strong>COSENZA<\/strong> &#8211; &nbsp;La Camera di Commercio di Cosenza, in collaborazione con la Fondazione Movimento Bambino e la&nbsp;Fondazione Ferrero, sono i promotori di una mostra<\/p>\n<p>  <!--more-->  <\/p>\n<p>fotografica sul variegato mondo dell\u2019infanzia dal&nbsp;titolo &#8220;BAMBINI, Anima del Mondo&#8221;, che si terr\u00e0 nella sede camerale di Cosenza dal prossimo luned\u00ec&nbsp;17 dicembre 2012 sino al 15 gennaio 2013. La tappa calabrese della mostra dar\u00e0 il via ad un lungo&nbsp;viaggio per il mondo, dopo che il prossimo 29 gennaio 2013 approder\u00e0 a Roma nelle sale del Senato&nbsp;della Repubblica e, successivamente, nella sede europea di Strasburgo. La rassegna, che si propone&nbsp;di riconoscere e rendere nota la sapienza dei bambini, sar\u00e0 strutturata in 70 pannelli fotografici&nbsp;con testi, tra i quali la Carta di Alba redatta dalla Fondazione Movimento Bambino sulla tutela&nbsp;dell\u2019infanzia e pubblicata nel libro &#8220;Bambini&#8221; di Alessandra Santelli e Maria Rita Parsi. Le foto della&nbsp;Santelli sono frammenti di viaggi, momenti, scoperte di un mondo che appartiene ai bambini e che&nbsp;tenta di contenerli nei suoi confini. I testi che accompagnano le istantanee sono attinti da un\u2019opera&nbsp;di Maria Rita Parsi, &#8220;Il pensiero bambino&#8221; che rappresenta un manifesto sulla filosofia bambina.&nbsp;Questa raccolta di parole e immagini non \u00e8 solo artistica, ma anche scientifica, giuridica e politica.&nbsp;La mostra rappresenta un\u2019operazione di conoscenza, di rivendicazione di un diritto fondamentale: il&nbsp;diritto all\u2019infanzia, ovvero quel principio pacificamente rivoluzionario che conferisce autorevolezza a&nbsp;chi, nel mondo, cos\u00ec com\u2019\u00e8 strutturato, non ha alcuna autorit\u00e0. &gt; La Camera di Commercio \u2013 dichiara il<\/p>\n<p>Presidente Gaglioti &#8211; ha ritenuto offrire il suo appoggio morale e organizzativo ad un\u2019 iniziativa che&nbsp;rientra negli interessi generali del sistema economico in termini di \u201csano\u201d sviluppo dell\u2019economia&nbsp;provinciale, che nasce e inizia dai bambini&gt;. Prosegue ancora sostenendo che, &gt; L\u2019ente camerale&nbsp;opera all\u2019educazione alla legalit\u00e0 con azioni in stretta sinergia con la Prefettura mediante la&nbsp;sottoscrizione di un protocollo d\u2019intesa e con il coinvolgimento con le scuole di ogni ordine e&nbsp;grado&gt;.<br \/>All\u2019evento inaugurativo della mostra prenderanno parte tutti gli organismi sociali e professionali&nbsp;interessati, insieme alle pi\u00f9 alte autorit\u00e0 civili, militari e religiose.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>COSENZA &#8211; &nbsp;La Camera di Commercio di Cosenza, in collaborazione con la Fondazione Movimento Bambino e la&nbsp;Fondazione Ferrero, sono i promotori di una mostra<\/p>\n","protected":false},"author":22,"featured_media":9659,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,563,42],"tags":[],"class_list":["post-9658","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-area-urbana","category-cosenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/9658","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=9658"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/9658\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/9659"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=9658"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=9658"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=9658"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}