{"id":96813,"date":"2018-08-08T10:49:38","date_gmt":"2018-08-08T08:49:38","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/mutilavano-le-vittime-per-truffare-le-assicurazioni-in-manette-11-persone\/"},"modified":"2023-01-16T18:57:37","modified_gmt":"2023-01-16T17:57:37","slug":"231651-mutilavano-le-vittime-per-truffare-le-assicurazioni-in-manette-11-persone","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/231651-mutilavano-le-vittime-per-truffare-le-assicurazioni-in-manette-11-persone\/","title":{"rendered":"Mutilavano le vittime per truffare le assicurazioni, in manette 11 persone"},"content":{"rendered":"<h4>Tra i fermati anche una infermiera dell&#8217;ospedale Civico di Palermo che procurava l&#8217;anestetico per attenuare i dolori dopo le mutilazioni subite. In molti finivano sulla sedia a rotelle o erano costretti a muoversi con le stampelle. Le indagini partirono dalla morte di un tunisino<\/h4>\n<p><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p><strong>PALERMO &#8211; <\/strong>Mutilavano braccia e gambe delle vittime, che erano consenzienti\u00a0nonostante a volte finissero in sedia a rotelle, sostenendo che quelle lesioni erano la conseguenza di incidenti stradali, in modo da poter poi truffare le assicurazioni.\u00a0\u00c8\u00a0quanto ha scoperto la Polizia a\u00a0Palermo\u00a0sgominando due pericolose organizzazioni criminali. I poliziotti stanno eseguendo 11 provvedimenti di fermo emessi dalla procura di\u00a0Palermo. Gli indagati sono 60.<\/p>\n<p>Tossicodipendenti, persone con problemi mentali o dipendenti dall&#8217;alcol,\u00a0soggetti in grave difficolt\u00e0 economica: erano tutti soggetti ai margini della societ\u00e0 le vittime delle due organizzazioni. Venivano gravemente feriti in cambio di poche centinaia di euro. Soggetti che, attratti dalla promessa &#8211; mai mantenuta &#8211; di ricevere del denaro, davano il loro consenso a subire ogni tipo di violenza. Uno dei capi sarebbe un perito assicurativo. Dalle indagini \u00e8 emerso che in alcune situazioni i membri delle associazioni criminali somministravano in maniera rudimentale dosi di anestetico alle vittime, per tentare di ridurre e attenuare il dolore delle mutilazioni subite. L&#8217;anestetico veniva procurato da una delle persone fermate, un&#8217;infermiera in servizio all&#8217;ospedale Civico di Palermo.<\/p>\n<p>E c&#8217;\u00e8 anche un tunisino che \u00e8 morto tra le vittime delle due organizzazioni scoperte della Polizia\u00a0. Le indagini degli uomini della squadra mobile di\u00a0Palermo\u00a0hanno infatti accertato che il cittadino tunisino Yakoub Hadry, trovato morto su una strada alla periferia di\u00a0Palermo\u00a0nel gennaio 2017, non era in realt\u00e0 rimasto vittima di un incidente stradale ma era deceduto in seguito alle fratture provocate dai membri di una delle due organizzazioni proprio con l&#8217;obiettivo di simulare un incidente e ottenere cos\u00ec i rimborsi assicurativi.\u00a0Proprio da quel falso incidente, sulla cui veridicit\u00e0 emersero subito sospetti, ha preso le mosse l&#8217;inchiesta\u00a0della Squadra mobile della Questura di Palermo.<\/p>\n<p>&nbsp;<\/p>\n<p><iframe loading=\"lazy\" title=\"Si facevano rompere le ossa per incassare i soldi dell&#039;assicurazione, le intercettazioni\" width=\"740\" height=\"416\" src=\"https:\/\/www.youtube.com\/embed\/s2g-UbxzZaU?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tra i fermati anche una infermiera dell&#8217;ospedale Civico di Palermo che procurava l&#8217;anestetico per attenuare i dolori dopo le mutilazioni subite. In molti finivano sulla sedia a rotelle o erano costretti a muoversi con le stampelle. Le indagini partirono dalla morte di un tunisino<\/p>\n","protected":false},"author":37,"featured_media":96814,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[16],"tags":[],"class_list":["post-96813","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-italia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/96813","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/37"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=96813"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/96813\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/96814"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=96813"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=96813"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=96813"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}