{"id":96815,"date":"2018-08-12T06:00:19","date_gmt":"2018-08-12T04:00:19","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/castrolibero-ripropone-il-progetto-anziani-alle-terme\/"},"modified":"2023-01-16T18:57:37","modified_gmt":"2023-01-16T17:57:37","slug":"231658-castrolibero-ripropone-il-progetto-anziani-alle-terme","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/231658-castrolibero-ripropone-il-progetto-anziani-alle-terme\/","title":{"rendered":"Castrolibero ripropone il progetto &#8220;Anziani alle Terme&#8221;"},"content":{"rendered":"<h4>L\u2019Amministrazione comunale di Castrolibero ripropone, anche per quest\u2019anno, il progetto rivolto ai cittadini che necessitano di cure termali, con la possibilit\u00e0 di dedicare tempo ed attenzioni al miglioramento della propria salute.<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>CASTROLIBERO (CS) &#8211; Sono aperte le iscrizioni per il servizio di accompagnamento dei residenti di Castrolibero presso le Terme di Guardia Piemontese. Possono partecipare al progetto gli <strong>over 65<\/strong>, se di sesso maschile, e gli over 60 se di sesso femminile, mentre per le persone portatrici di handicap, non sono previsti limiti di et\u00e0. Le domande di partecipazione una volta compilate, su apposito modulo, disponibile presso l&#8217;Ufficio dei Servizi Sociali o scaricabile sul sito istituzionale del <span style=\"color: #0000ff;\"><a style=\"color: #0000ff;\" href=\"https:\/\/quicosenza.it\/news\/5439\" target=\"_blank\" rel=\"noopener\">Comune\u00a0\u00a0<\/a><\/span>vanno presentate<strong>, entro e non oltre il 3 settembre 2018,<\/strong> all&#8217;Ufficio dei Servizi Sociali sito in Via Papa Bonifacio VIII oppure al Protocollo Generale del Comune di Via XX Settembre.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-177033 alignleft\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2017\/09\/Foto-Sindaco-castrolibero-Giovanni-Greco.jpg\" alt=\"\" width=\"241\" height=\"407\" title=\"\">\u00abSiamo lieti di garantire, come d\u2019altronde accade gi\u00e0 da svariati anni, questo importante servizio per i nostri concittadini \u2013 dichiara il Sindaco <strong>Giovanni Greco<\/strong> &#8211; in quanto, oltre agli aspetti strettamente salutistici, rappresenta un momento di incontro e di convivialit\u00e0 per quanti intendono dare la loro disponibilit\u00e0 a partecipare. In realt\u00e0, sono sempre pi\u00f9 numerose le persone che, di volta in volta, aderiscono al progetto. Ci\u00f2 sta a dimostrare l\u2019importanza ed il valore sociale della nostra proposta, sia in termini preventivi e terapeutici per la cura di determinate patologie che possono insorgere nel corso della cosiddetta \u201cterza et\u00e0\u201d, che sul fronte delle attivit\u00e0 pi\u00f9 strettamente ricreative e di socializzazione che il Comune da tempo predispone a favore di questa fascia di popolazione, facendo in modo che questa fase della vita sia possibilmente sempre pi\u00f9 attiva, propositiva ed inclusiva\u00bb.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019Amministrazione comunale di Castrolibero ripropone, anche per quest\u2019anno, il progetto rivolto ai cittadini che necessitano di cure termali, con la possibilit\u00e0 di dedicare tempo ed attenzioni al miglioramento della propria salute.<\/p>\n","protected":false},"author":22,"featured_media":96816,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[564,571],"tags":[],"class_list":["post-96815","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-castrolibero","category-in-evidenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/96815","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=96815"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/96815\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/96816"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=96815"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=96815"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=96815"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}