{"id":96833,"date":"2018-08-17T18:27:32","date_gmt":"2018-08-17T16:27:32","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/revocato-provvedimento-per-un-uomo-in-divisa-segnalato-per-stalking\/"},"modified":"2023-01-16T18:57:38","modified_gmt":"2023-01-16T17:57:38","slug":"231709-revocato-provvedimento-per-un-uomo-in-divisa-segnalato-per-stalking","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/231709-revocato-provvedimento-per-un-uomo-in-divisa-segnalato-per-stalking\/","title":{"rendered":"Revocato provvedimento per un uomo in divisa segnalato per stalking"},"content":{"rendered":"<h4>&#8220;Ricevevo da lui anche sessanta telefonate al giorno&#8221;. Lo sfogo dell&#8217;ex compagna che terrorizzata lamenta di essere stata delusa dalle istituzioni<\/h4>\n<p><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p>COSENZA &#8211; Una donna di Cosenza lamenta di non sentirsi tutelata dalle autorit\u00e0 a cui si \u00e8 rivolta per chiedere aiuto. Le sue richieste sono state inizialmente accolte, ma adesso l&#8217;uomo che da un anno l&#8217;ossessionava ha ottenuto la revoca del provvedimento emesso a suo carico. Si tratta di un<strong> cinquantenne che indossa la divisa e che dall&#8217;avvio delle indagini non ha pi\u00f9 posto in essere alcun tentativo di approccio con la sua ex<\/strong> <strong>compagna<\/strong>. Nei mesi precedenti per\u00f2 era arrivato sino al punto di pedinarla, appostarsi vicino casa e di telefonarle fino a sessanta volte al giorno. Nel suo appello la donna chiede all&#8217;autorit\u00e0 se vi siano mai stati altri casi di revoca in tempi cos\u00ec rapidi.\u00a0<em><strong>\u00a0<\/strong><\/em><\/p>\n<p>&nbsp;<\/p>\n<p>&#8220;La violenza, &#8211; scrive la donna cosentina che per mesi \u00e8 stata oggetto delle attenzioni &#8216;morbose&#8217; del suo ex compagno &#8211; non \u00e8 solo uno schiaffo o portare dei lividi sul corpo. E&#8217; molto di pi\u00f9. E\u2019 vergogna, \u00e8 paura, \u00e8 ansia, \u00e8 timore di non essere compresi, \u00e8 timore di non essere creduti, \u00e8 sopratutto la consapevolezza di scontrarsi con il sospetto che chi \u00e8 preposto non ti aiuti. Puoi anche accettare l&#8217;omert\u00e0 intorno a te, ma non il senso di abbandono che percepisci confrontandoti con le istituzioni a cui ti rivolgi per chiedere tutela, protezione, aiuto e supporto. Da anni si legge che Forze dell\u2019Ordine ed Enti vari, avviano continue campagne per sensibilizzare le donne, che subiscono silenziosamente violenza, inducendole a <strong>denunciare, ad uscire dal silenzio, a farsi coraggio, a fidarsi ed affidarsi alle Istituzioni<\/strong>\u00a0gridando contro chi fa leva in modo vigliacco, su stati di ansia e paura.<\/p>\n<p>&nbsp;<\/p>\n<p>E poi? Cosa succede? <strong>Difficile immaginarlo se non hai \u201ctoccato con mano\u201d, ma io si lo so bene e voglio raccontare la mia storia<\/strong> e nello specifico cosa succede. Varchi la soglia dell&#8217;Istituzione alla quale decidi di chiedere aiuto e tutela, dopo un&#8217;enorme sofferenza e disagio, difficile da spiegare e quasi impossibile da comprendere, con un senso finalmente di sollievo e pensando che ti accoglieranno, dandoti tranquillit\u00e0, serenit\u00e0 e protezione. Sin dal primo approccio, per quanto mi riguarda, ho riscontrato invece atteggiamenti ostili. Avrei voluto sentirmi dire &#8216;tranquilla, ora ci siamo noi&#8217;, per\u00f2 ho trovato scarsa considerazione, atteggiamenti volti a scoraggiarmi, sguardi solo di curiosit\u00e0, nessun beneficio del dubbio (almeno nel primo momento). Mi sono trovata &#8216;sbattuta&#8217; da un ufficio all&#8217;altro con poco tatto. Nonostante avessi appreso dalle varie campagne di sensibilizzazione che esiste un ufficio e gente che dovrebbe occuparsi solo di questo mi ero premurata di portare con me una richiesta scritta per segnalare la mia situazione di estremo disagio.<\/p>\n<p>&nbsp;<\/p>\n<p>Un foglio che \u00e8 passato da un dipendente all&#8217;altro per ore alla ricerca di qualcuno preposto ad apporre una semplice firma e un numero di protocollo. Alle 9:30 del mattino di marted\u00ec non c&#8217;era nessuno ad accogliere una donna in difficolt\u00e0, ho aspettato nei corridoi, mentre oltre 15 impiegati a turno hanno fatto il passamano della mia istanza: facevano telefonate, si allontanavano, mi chiudevano la porta davanti, mentre io continuavo ad attendere in piedi in corridoio. <strong>Non c&#8217;era nessuno che potesse firmare la segnalazione contro il collega presunto stalker.\u00a0<\/strong>Poi mi sono infastidita, ho preteso che fosse protocollata e sono andata via\u00a0demotivata, delusa e incredula, dalla leggerezza con la quale viene gestita una richiesta di aiuto per violenza di genere. Ho dovuto aspettare il mattino seguente quando sono stata invitata a ritornare per firmare un \u201cverbale di ratifica\u201d che probabilmente poteva essere compilato il giorno prima.<\/p>\n<p>&nbsp;<\/p>\n<p>Inizia cos\u00ec una triste vicenda, con un fine incredibile che racconter\u00f2 solo in parte dovendo omettere nomi ed episodi non documentabili. Dopo la segnalazione ricca anche di messaggi e telefonate che provavano ci\u00f2 che sostenevo la<strong>\u00a0persona segnalata, che peraltro porta una divisa, ha continuato ad assillarmi, incurante della richiesta depositata. <\/strong>Mi ha angustiata\u00a0per oltre 15 giorni fino a quando, incredula, mi sono nuovamente rivolta all\u2019Autorit\u00e0 integrando la richiesta con altra documentazione attestante i contatti successivi e chiedendo impaurita che questo soggetto fosse allertato e allontanato da me. Le indagini sono poi durate quattro mesi, alla fine dei quali \u00e8 arrivato finalmente l&#8217;inevitabile provvedimento amministrativo richiesto. Provvedimento al quale, lo stalker, come da sua facolt\u00e0, si \u00e8 opposto facendo ricorso al TAR. La sua richiesta \u00e8 stata per\u00f2 rigettata e ho pensato: &#8216;finalmente \u00e8 finita, sanno che ho ragione. Ho fatto bene a denunciare&#8217;.<\/p>\n<p>&nbsp;<\/p>\n<p>Invece no. Dopo soli 20 giorni dall&#8217;ordinanza del TAR il mio ex compagno ha chiesto di nuovo la revoca del provvedimento e in data 27 luglio 2018 l&#8217;ha ottenuta, firmata dalla stessa persona che lo aveva emesso.\u00a0Ha &#8216;fatto il bravo&#8217; sei mesi, queste le loro motivazioni. A chi ha firmato questa revoca chiedo il perch\u00e9, visto che solo 20 giorni prima la stessa Autorit\u00e0 si era opposta in modo fermo all\u2019annullamento. Come mai un cambio cos\u00ec repentino di idee? Donne: denunciate, denunciate. Non abbiate timore, cos\u00ec dicono, ma la realt\u00e0 per me \u00e8 stata diversa. Mi sono sentita come se la mia dignit\u00e0, i miei diritti, il mio dolore e la mia sofferenza fossero stati calpestati. Sono stata costretta a difendermi a mie spese. State attente a chi denunciate. A\u00a0prescindere dalla mia vicenda personale, non ritengo accettabile nelle Istituzioni, <strong>nelle quali sottolineo di aver incontrato anche esempi di persone splendide e aperte al dialogo<\/strong>, ve ne siano altre che cos\u00ec operando non fanno sentire tutelato chi denuncia. In ogni caso mi sforzer\u00f2 a dare ancora loro fiducia opponendomi legalmente a questa revoca&#8221;.<\/p>\n<p>&nbsp;<\/p>\n<p>L&#8217;Autorit\u00e0 a cui la donna si \u00e8 rivolta, contattata dalla redazione, ha confermato la vicenda, affermando che per\u00f2 vi sono stati alcuni fraintendimenti.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;Ricevevo da lui anche sessanta telefonate al giorno&#8221;. Lo sfogo dell&#8217;ex compagna che terrorizzata lamenta di essere stata delusa dalle istituzioni<\/p>\n","protected":false},"author":22,"featured_media":96834,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[42],"tags":[],"class_list":["post-96833","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cosenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/96833","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=96833"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/96833\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/96834"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=96833"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=96833"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=96833"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}