{"id":9716,"date":"2012-12-14T19:42:23","date_gmt":"2012-12-14T18:42:23","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=9716"},"modified":"2023-01-17T13:42:52","modified_gmt":"2023-01-17T12:42:52","slug":"4321-auto-in-fiamme-i-vigili-evitano-linferno","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/4321-auto-in-fiamme-i-vigili-evitano-linferno\/","title":{"rendered":"Auto in fiamme: i vigili evitano l&#8217;inferno"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>MONTALTO &#8211;<\/strong> Inneschi di paura. E&#8217; di due auto distrutte e tante altre salvate, il bilancio di un incendio, verificatosi nei<strong> pressi del parcheggio adiacente il Comac di Montalto Uffugo<\/strong>. Le fiamme, domate<\/p>\n<p>  <!--more-->  <\/p>\n<p style=\"text-align: justify;\">tempestivamente<strong> dai vigili del fuoco del Comando provinciale di Cosenza e dai loro colleghi del distaccamento di Rende,<\/strong> non hanno causato ulteriori danni. Mentre i pompieri, spegnevano le fiamme, mettevano in sicurezza le auto ed effettuavano un sopralluogo tecnico nell&#8217;area, alla ricerca di eventuali altri focolai spontanei ancora attivi, i carabinieri della stazione di Montalto, intervenivano sulla scena dell&#8217;incendio per le indagini di loro competenza. Le ipotesi al vaglio degli inquirenti sono diverse.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>MONTALTO &#8211; Inneschi di paura. E&#8217; di due auto distrutte e tante altre salvate, il bilancio di un incendio, verificatosi nei pressi del parcheggio adiacente il Comac di Montalto Uffugo. Le fiamme, domate<\/p>\n","protected":false},"author":22,"featured_media":9717,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,17],"tags":[],"class_list":["post-9716","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/9716","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=9716"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/9716\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/9717"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=9716"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=9716"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=9716"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}