{"id":9734,"date":"2012-12-15T15:08:12","date_gmt":"2012-12-15T14:08:12","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=9734"},"modified":"2023-01-17T13:42:53","modified_gmt":"2023-01-17T12:42:53","slug":"4330-i-lavoratori-del-call-center-i-nostri-diritti-sono-rispettati","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/4330-i-lavoratori-del-call-center-i-nostri-diritti-sono-rispettati\/","title":{"rendered":"I lavoratori del call center: i nostri diritti sono rispettati"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>MONTALTO UFFUGO &#8211;<\/strong> Se il turno &#8220;A&#8221; attacca, quello &#8220;B&#8221; difende. Relativamente all&#8217;articolo sulle presunte inefficienze organizzative e gestionali, portate alla luce da un gruppo di dipendenti dell&#8217;Outbound<\/p>\n<p>  <!--more-->  <\/p>\n<p style=\"text-align: justify;\">Vodafone di Abramo Customercare, diamo voce ad una controreplica di altri dipendenti che, smentiscono i loro colleghi, inoltrandoci, tramite un comunicato stampa, raccontano la loro versione dei fatti ristabilendo, secondo loro, la verit\u00e0. Non e&#8217; il nostro call center ad essere un &#8220;bluff&#8221;, ma sono coloro che falsamente e duramente ci attaccano immotivatamente. Sar\u00e0 la competizione? Sar\u00e0 chi dall&#8217;altra parte vuol far vedere o tergiversare cose che nella realta&#8217; non esistono. Gli operatori Senior lavorano da circa quattro anni in questo armonioso reparto. E&#8217; pur vero che da settembre abbiamo una nuova sede, decentrata rispetto a quella principale, ma non reputiamo affatto che sia un lager. E&#8217; provvista di illuminazione esterna e non e&#8217; infestata da erbacce.Quest&#8217;ultime sono presenti nel territorio periferico adiacente alla sede, tra l&#8217;altro ben collocata e dotata di parcheggi esterni. Un&#8217;impresa di pulizia ne gestisce in mattinata e nel pomeriggio la cura interna ed esterna alla struttura. Si lavora ogni giorno e non sicuramente guadagnando solo 20 euro a singola attivazione telefonica. Non e&#8217; affatto vero che chi offre lavoro scrupoli non se ne fa. Non ci sentiamo costretti ad accettare nessun compromesso per raggrenellare i soldi per arrivare a fine mese. I nostri stipendi sono puntuali e congrui all&#8217;attivit\u00e0 lavorativa espletata, non si spiegherebbe il motivo per il quale siamo numerosi e facciamo questo lavoro da diversi anni. Il nostro staff \u00e8 composto da personale qualificato e sempre attento e disponibile alle dinamiche lavorative interne. I Criteri contrattuali sono quelli del Co Co Pro. I nostri orari lavorativi partono dalle ore 9 alle 21, ed ognuno di noi gestisce con molta autonomia e flessibilit\u00e0 la propria attivit\u00e0 lavorativa da sempre. Ci dissociamo dal vostro articolo, in quanto non corrisponde alla realta&#8217; ne&#8217; ambientale, n\u00e8 lavorativa.<\/p>\n<p style=\"text-align: justify;\">TUTTI GLI OPERATORI OUTBOUND VODAFONE DI ABRAMO CUSTOMERCARE.&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>MONTALTO UFFUGO &#8211; Se il turno &#8220;A&#8221; attacca, quello &#8220;B&#8221; difende. Relativamente all&#8217;articolo sulle presunte inefficienze organizzative e gestionali, portate alla luce da un gruppo di dipendenti dell&#8217;Outbound<\/p>\n","protected":false},"author":22,"featured_media":9735,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,17],"tags":[],"class_list":["post-9734","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/9734","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=9734"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/9734\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/9735"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=9734"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=9734"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=9734"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}