{"id":97527,"date":"2018-08-27T15:36:40","date_gmt":"2018-08-27T13:36:40","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/passeggero-litiga-per-un-posto-inesistente-la-polizia-lo-allontana-dallaereo\/"},"modified":"2023-01-16T18:58:25","modified_gmt":"2023-01-16T17:58:25","slug":"234643-passeggero-litiga-per-un-posto-inesistente-la-polizia-lo-allontana-dallaereo","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/234643-passeggero-litiga-per-un-posto-inesistente-la-polizia-lo-allontana-dallaereo\/","title":{"rendered":"Passeggero litiga per un posto inesistente, la polizia lo allontana dall&#8217;aereo"},"content":{"rendered":"<h4>Aveva acquistato un biglietto per un volo con partenza da Lamezia Terme, ma la compagnia aerea erroneamente gli aveva assegnato un posto in una fila che non esiste<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>TORINO &#8211; Passeggero a terra per aver contestato un disservizio. Per errore gli era stato assegnato un posto in una fila inesistente sull&#8217;aereo, ne ha occupato un altro a suo piacimento e quando l&#8217;hostess gliene ha trovato uno libero, ha reagito con veemenza aggredendo un dipendente dell&#8217;aeroporto che cercava di convincerlo. Alla fine il comandante lo ha allontanato dal velivolo, lasciandolo a terra. E&#8217; successo, oggi pomeriggio, su volo Blue Air da Lamezia Terme a Torino. L&#8217;uomo, che viaggiava con la moglie, ha occupato un posto che non era suo (in seconda fila) perch\u00e9 su quell&#8217;aereo non esiste la fila 1 che gli era stata assegnata sulla carta di imbarco. Le hostess lo hanno invitato a spostarsi, assegnandogli un&#8217;altra sistemazione ma il passeggero si \u00e8 rifiutato e ha aggredito il dipendente dell&#8217;aeroporto. Il comandante a quel punto ha chiesto l&#8217;intervento della<strong> polizia che \u00e8 salita a bordo e ha invitato il passeggero agitato a lasciare l&#8217;aereo<\/strong>. Anche la moglie \u00e8 scesa. Il volo Lamezia Terme-Torino \u00e8 decollato con oltre mezz&#8217;ora di ritardo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Aveva acquistato un biglietto per un volo con partenza da Lamezia Terme, ma la compagnia aerea erroneamente gli aveva assegnato un posto in una fila che non esiste<\/p>\n","protected":false},"author":22,"featured_media":97528,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[16],"tags":[],"class_list":["post-97527","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-italia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/97527","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=97527"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/97527\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/97528"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=97527"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=97527"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=97527"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}