{"id":9754,"date":"2012-12-16T20:44:25","date_gmt":"2012-12-16T19:44:25","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=9754"},"modified":"2023-01-17T13:42:54","modified_gmt":"2023-01-17T12:42:54","slug":"4345-telethon-certifica-il-gran-cuore-dei-cosentini","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/4345-telethon-certifica-il-gran-cuore-dei-cosentini\/","title":{"rendered":"Telethon certifica il gran cuore dei cosentini"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>COSENZA &#8211;<\/strong> Gente di cuore. Tra i calabresi e la solidariet\u00e0 c&#8217;\u00e8 un grande feeling, un feeling che non conosce tali, nemmeno in tempo di crisi. Il gran cuore dei calabresi, i cosentini in particolare, ha fatto crescere,<\/p>\n<p>  <!--more-->  <\/p>\n<p style=\"text-align: justify;\">di molto, il totalizzatore di Telethon. Lo dicono i dati. La Calabria, secondo i primi dati, ha donato a Telethon, attraverso Bnl, la somma di 268.480 euro. <strong>La raccolta 2012 si chiude il 31 dicembre. Un risultato che ha visto protagonista Cosenza con 90.660 euro. Catanzaro ha raccolto 65.895 euro; Crotone 24.800 euro; Reggio Calabria 65.720 euro e, infine, Vibo Valentia ha contribuito alla raccolta fondi Bnl con 21.405 euro.<\/strong> \u00abBnl \u2013 \u00e8 scritto in una nota \u2013 \u00e8 da oltre vent&#8217;anni il principale partner della Fondazione Telethon e, anche in questa edizione, ha ottenuto uno straordinario risultato a livello nazionale con circa 11 milioni di euro. Dal 1992 ad oggi, la Banca ha raccolto complessivamente 234 milioni di euro. La partnership Bnl per Telethon si posiziona tra i maggiori progetti di fund raising in Europa. Bnl Gruppo Bnp Paribas ringrazia la Calabria per il contributo offerto al successo di Telethon 2012 e per la generosit\u00e0\u2026 di tante persone che, insieme alla Banca, si sono impegnate nella raccolta fondi a favore della ricerca scientifica sulle malattie genetiche\u00bb. \u00abL&#8217;impegno di Bnl per Telethon \u2013 prosegue la nota \u2013 non si esaurisce nei giorni della maratona, ma prosegue tutto l&#8217;anno per sensibilizzare clienti e non sui temi della ricerca. Bnl organizza eventi di raccolta e mette a disposizione di coloro che vogliono continuare a fare donazioni sia gli sportelli della Banca sia, per i clienti, tutti i suoi Atm, il canale telefonico (numero verde 800900900 o +390687408740 dall&#8217;estero o dai cellulari) e quello on line (bnl.it). La presenza di Bnl sul web si estende ulteriormente, grazie alla fan page Bnl per Telethon su Facebook, tutti (clienti e non) possono seguire gli eventi Bnl per Telethon ed effettuare donazioni online, tramite carta di credito\u00bb.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>COSENZA &#8211; Gente di cuore. Tra i calabresi e la solidariet\u00e0 c&#8217;\u00e8 un grande feeling, un feeling che non conosce tali, nemmeno in tempo di crisi. Il gran cuore dei calabresi, i cosentini in particolare, ha fatto crescere,<\/p>\n","protected":false},"author":22,"featured_media":9755,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,17],"tags":[],"class_list":["post-9754","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/9754","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=9754"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/9754\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/9755"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=9754"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=9754"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=9754"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}