{"id":9758,"date":"2012-12-16T21:08:24","date_gmt":"2012-12-16T20:08:24","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=9758"},"modified":"2023-01-17T13:42:55","modified_gmt":"2023-01-17T12:42:55","slug":"4347-suicidi-in-carcere-lanalisi-di-emilio-quintieri-fermare-subito-la-mattanza","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/4347-suicidi-in-carcere-lanalisi-di-emilio-quintieri-fermare-subito-la-mattanza\/","title":{"rendered":"Suicidi in carcere, l&#8217;analisi di Emilio Quintieri: fermare subito la mattanza"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>COSENZA &#8211;<\/strong> Morire di carcere. Mentre Marco Pannella, Leader dei Radicali, da giorni \u00e8 in totale sciopero della fame e della sete rischiando seriamente la propria vita per richiamare l&#8217;attenzione delle Istituzioni<\/p>\n<p>  <!--more-->  <\/p>\n<p style=\"text-align: justify;\">Nazionali ed Internazionali sulla comatosa situazione in cui versa la nostra Giustizia Penale e le Carceri, oggi si \u00e8 suicidato un&#8217;altro giovane di 24 anni, incensurato, residente ad Augusta (Siracusa) arrestato dai carabinieri nei giorni scorsi per i reati di resistenza ed oltraggio a Pubblico Ufficiale.<strong> L&#8217;ennesima storia di morte di carcere \u00e8 raccontata da Emilio Quntieri, l&#8217;ecologista radicale di Cetraro che sulla questione del sovraffollamento delle carceri, sulla necessit\u00e0 di fare una riforma giusta della giustizia e sull&#8217;opportunit\u00e0 di fermare questa strage d&#8217;innocenti.<\/strong> Si \u00e8 impiccato con una corda ad un infisso della sua momentanea dimora ove si trovava ristretto agli arresti domiciliari. A scoprire quanto accaduto sono stati proprio i Carabinieri durante un normale controllo con l&#8217;ausilio dei Vigili del Fuoco che hanno sfondato la porta dell&#8217;abitazione. Si chiamava Francesco Marino e gi\u00e0 in precedenza aveva tentato con gesti estremi di porre fine alla sua vita terrena. Aveva gravi problemi psichiatrici ed era molto depresso; i reati contestati si erano verificati all&#8217;interno dell&#8217;abitazione dei suoi genitori durante una rissa con gli stessi scoppiata tra le mura domestiche. Per quale motivo l&#8217;Autorit\u00e0 Giudiziaria ha applicato la misura cautelare degli arresti domiciliari a questo ragazzo nonostante la sua completa incensuratezza e la sua non pericolosit\u00e0 sociale ? Per quale motivo, tenuto conto dei suoi problemi psichiatrici e dei gesti autolesionistici precedentemente posti in essere, l&#8217;Autorit\u00e0 Giudiziaria non ha disposto il suo ricovero presso un Ospedale Psichiatrico Giudiziario o comunque presso un luogo di cura o di assistenza o di accoglienza ? Salgono a 153 i &#8220;morti di pena&#8221; da gennaio 2012, 60 dei quali si sono tolti la vita. Dal 2000 ad oggi, invece, le persone private della libert\u00e0 decedute sono 2.086 dei quali 751 per suicidio. La Repubblica Italiana? Chiude con una domanda Quintieri. Uno STATO CRIMINALE !!!!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>COSENZA &#8211; Morire di carcere. Mentre Marco Pannella, Leader dei Radicali, da giorni \u00e8 in totale sciopero della fame e della sete rischiando seriamente la propria vita per richiamare l&#8217;attenzione delle Istituzioni<\/p>\n","protected":false},"author":22,"featured_media":9759,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,17],"tags":[],"class_list":["post-9758","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/9758","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=9758"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/9758\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/9759"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=9758"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=9758"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=9758"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}