{"id":97671,"date":"2018-08-31T20:30:03","date_gmt":"2018-08-31T18:30:03","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/raccolta-differenziata-a-cosenza-sabato-non-si-espongono-i-mastelli\/"},"modified":"2023-01-16T18:58:36","modified_gmt":"2023-01-16T17:58:36","slug":"235217-raccolta-differenziata-a-cosenza-sabato-non-si-espongono-i-mastelli","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/235217-raccolta-differenziata-a-cosenza-sabato-non-si-espongono-i-mastelli\/","title":{"rendered":"Raccolta differenziata a Cosenza, sabato non si espongono i mastelli"},"content":{"rendered":"<h4>La raccolta del vetro continuer\u00e0 ad essere effettuata di mercoled\u00ec come nelle scorse settimane<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>COSENZA &#8211; Il servizio di raccolta del vetro per le utenze domestiche della citt\u00e0 di Cosenza continua in via sperimentale ad essere effettuato non pi\u00f9 alla domenica, ma di mercoled\u00ec. Pi\u00f9 precisamente con le stesse modalit\u00e0 adottate a partire da mercoled\u00ec 8 agosto si dovr\u00e0 conferire,<strong>\u00a0mercoled\u00ec dalle ore 6.00 alle ore 8.00 del mattino la frazione del vetro<\/strong> nelle apposite attrezzature. I mastelli non saranno quindi pi\u00f9 esposti di sabato sera. Si informano le utenze che gli altri conferimenti restano immutati.\u200b<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La raccolta del vetro continuer\u00e0 ad essere effettuata di mercoled\u00ec come nelle scorse settimane<\/p>\n","protected":false},"author":22,"featured_media":97672,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17,42,40,13,70],"tags":[],"class_list":["post-97671","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria","category-cosenza","category-cultura-spettacolo","category-qui-green","category-quiecologia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/97671","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=97671"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/97671\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/97672"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=97671"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=97671"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=97671"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}