{"id":97985,"date":"2018-09-10T14:02:54","date_gmt":"2018-09-10T12:02:54","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/cosenza-vecchia-pedonalizzata-senza-parcheggi-per-i-residenti-il-comune-oltre-500-auto-non-ce-posto\/"},"modified":"2023-01-16T18:58:58","modified_gmt":"2023-01-16T17:58:58","slug":"236268-cosenza-vecchia-pedonalizzata-senza-parcheggi-per-i-residenti-il-comune-oltre-500-auto-non-ce-posto","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/236268-cosenza-vecchia-pedonalizzata-senza-parcheggi-per-i-residenti-il-comune-oltre-500-auto-non-ce-posto\/","title":{"rendered":"Cosenza Vecchia pedonalizzata senza parcheggi per residenti, il Comune: &#8220;Hanno 500 auto, sono troppe&#8221;"},"content":{"rendered":"<h4>Raffiche di multe per i residenti, trenta nella sola giornata di mercoled\u00ec, a causa di comunicazioni errate da parte del Comune. Poche decine di parcheggi gratuiti per circa cinquecento automobili<\/h4>\n<p><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p>COSENZA &#8211; Incubo parcheggi per i residenti del centro storico. Con la chiusura al transito di corso Telesio chi vi abita con estrema difficolt\u00e0 riesce a posteggiare la propria auto. A Cosenza Vecchia infatti <strong>non \u00e8 previsto il rilascio di parking card che permettano ai residenti di utilizzare gli stalli con le strisce blu. L&#8217;intero centro storico non \u00e8 stato inserito nel Piano della Sosta redatto dal Comune<\/strong>. In pi\u00f9 mentre negli altri quartieri la sosta a pagamento \u00e8 prevista nei giorni feriali, dal luned\u00ec al sabato, dalle 8:00 alle 20:00. A Cosenza Vecchia il divieto vige per l&#8217;intero arco della giornata: oo &#8211; 24.\u00a0La scorsa settimana in un solo giorno sono state emesse ben 30 multe a carico dei residenti che avevano parcheggiato nel piazzale che si trova alle spalle della Casa delle Culture. Dall&#8217;Amaco che gestisce gli stalli affermano che la societ\u00e0 emette i verbali &#8220;in base a quello che la legge prescrive. Il Comune di Cosenza ci ha detto di trattare quell&#8217;area come un normalissimo parcheggio con stalli a pagamento. E cos\u00ec stiamo operando&#8221;.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Le informazioni ricevute dai cittadini per\u00f2 sembrerebbero diverse.\u00a0&#8220;Ai residenti &#8211; afferma un uomo che abita vicino al Duomo &#8211; \u00e8 stato concesso un pass con il quale \u00e8 permesso sostare non pi\u00f9 di venti minuti sul corso principale, per\u00f2 si pu\u00f2 parcheggiare sul Lungo Crati e nel parcheggio grande di fronte l&#8217;Arenella. Almeno cos\u00ec ci avevano garantito. Dopo circa 15 giorni hanno fatto le strisce blu dove avremmo dovuto poter parcheggiare, invece <strong>pur esponendo il pass siamo stati multati: 41 euro ad auto. La mia famiglia che possiede due auto dovr\u00e0 quindi pagare 82 euro.<\/strong> La Polizia Municipale ha detto che non sapeva nulla e siamo rimasti esterrefatti&#8221;. Dal comando della Polizia Municipale fanno infatti sapere di non avere alcuna informazione in merito perch\u00e9 della gestione del parcheggio se ne occupa esclusivamente l&#8217;Amaco, ma sono disposti ad accogliere i ricorsi dei residenti sanzionati.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<h3>IL PARCHEGGIO C&#8217;E&#8217;, MA NON SI TROVA<\/h3>\n<p>A chiarire l&#8217;assurdit\u00e0 della situazione \u00e8 Michelangelo Spataro assessore alla Mobilit\u00e0 Sostenibile del Comune di Cosenza. &#8220;Nel parcheggio sul Lungo Crati alle spalle della Casa delle Culture <strong>ci sono in tutto 40 parcheggi a fronte di una richiesta di oltre 500 permessi per residenti che dovremmo rilasciare se attivassimo la parking card come negli altri quartieri di Cosenza.<\/strong> Per assegnarli dovremmo fare una graduatoria e non \u00e8 possibile. Oltre tutto quelle strisce blu non sono nel Piano della Sosta che prevede le strisce bianche in numero proporzionale perch\u00e9 il centro storico non \u00e8 stato contemplato. In quell&#8217;area infatti abbiamo previsto 10\/15 parcheggi gratuiti. I residenti del centro storico possono quindi parcheggiare senza pagare nelle traverse interne, su piazza dei Valdesi, sopra nella zona Porta Piana, Arco di Ciaccio, sul Lungo Fiume e, pi\u00f9 in generale, dove trovano posto. Che poi il parcheggio si trova, si fa fatica quando ci sono gli eventi, ma non \u00e8 un problema. La questione di quel parcheggio sorge ora che \u00e8 stato regolamentato quel piazzale prima gestito dagli abusivi. E&#8217; una protesta montata perch\u00e9 prima nessuno dei cittadini che abitavano a Cosenza Vecchia parcheggiava l\u00ec&#8221;.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Chi esce poco si trova a dover pagare per tenere l&#8217;auto ferma sotto casa almeno 12 euro. &#8220;Il pass che ci hanno dato al Comune &#8211; spiega la moglie di un disabile che abita nei pressi del Duomo &#8211; non d\u00e0 diritto a parcheggiare nelle strisce blu che hanno dipinto a terra solo qualche giorno fa. Prima tra corso Telesio e piazza Toscano riuscivamo a trovare stalli liberi ora \u00e8 un inferno arrivare a casa portando la spesa sui gradini a tre chilometri di distanza. Se era vietato parcheggiare perch\u00e9 non ci hanno informati? Era stato lo stesso ufficio che ci ha rilasciato il pass a dirci che nel parcheggio di fronte l&#8217;Arenella sotto la Casa delle Culture potevamo lasciare le auto. Poi hanno multato tutti dicendo che dobbiamo pagare il parchimetro: <strong>24 euro al giorno, per due auto 48 euro. E&#8217; una rapina.\u00a0Faccio pulizie, mi alzo alle 5:00 del mattino e guadagno 350 euro al mese non posso permettermelo.<\/strong> Ci proponessero un abbonamento che lo compriamo, per\u00f2 una soluzione devono darcela. Le strisce bianche sono sempre occupate, perch\u00e9 tra i nostri palazzi siamo almeno 300 le famiglie motorizzate. Dove me la metto la macchina? Mi marito \u00e8 invalido non posso lasciarla a Porta Piana. Le navette non risolvono il problema, lo dimostra il fatto che viaggiano a vuoto&#8221;.<\/p>\n<p>&nbsp;<\/p>\n<h3>IL PIANO GENERALE DELLA SOSTA<\/h3>\n<p>Il Piano Generale della Sosta che esclude Cosenza Vecchia dalle aree regolamentate da parking card divide la citt\u00e0 in quattro zone:\u00a0rossa (da via Lungo Busento fino a viale della Repubblica);\u00a0arancio (centro citt\u00e0);\u00a0verde (da Viale della Repubblica fino a via Popilia) e\u00a0gialla (da via Panebianco a viale Crati). Studiato partendo dall&#8217;assunto che &#8220;le auto ferme, quelle in sosta nelle strade, sono una causa importante, se non la principale, della congestione del traffico, dell\u2019inquinamento urbano e dei tempi spaventosamente lunghi per gli spostamenti urbani. Gli spazi da destinare alla sosta ed alla circolazione sono chiaramente insufficienti rispetto alle necessit\u00e0. Lo spazio stradale nelle citt\u00e0 \u00e8 un bene raro e perci\u00f2 caro. <strong>Chi lo occupa arreca un danno e genera costi a tutta la collettivit\u00e0 ed \u00e8 per questo che deve essere chiamato a contribuire a sostenerli&#8221;. <\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>L&#8217;obiettivo era come si legge nel documento elaborato dal 7\u00b0 Settore Infrastrutture &#8211; Mobilit\u00e0 del Comune di Cosenza e approvato dal Consiglio comunale: &#8220;lo scoraggiamento della sosta non necessaria; la promozione dell\u2019utilizzo dei servizi di trasporto pubblico; la razionalizzazione della movimentazione nelle aree pi\u00f9 congestionate; la diminuzione dell\u2019inquinamento atmosferico ed acustico; il corretto utilizzo di una risorsa scarsamente disponibile quale il suolo pubblico destinato alla sosta e alla circolazione&#8221;. Il piano si basava sui dati Istat del 2001 su Cosenza\u00a0&#8220;dei residenti nelle aree a pagamento dai quali si evidenziava che tale misura avrebbe riguardato circa 30.000 abitanti e quasi 14.000 nuclei familiari con una disponibilit\u00e0 <strong>14.615 auto. Il territorio cittadino veniva diviso in 4\u00a0settori che prevedevano 3.500 posti auto per la sosta a pagamento e 5.892 posti per la sosta libera<\/strong>&#8220;. Per gli altri invece l&#8217;unica possibilit\u00e0 e vendere l&#8217;auto e spostarsi a piedi. Questa la mobilit\u00e0 sostenibile &#8216;forzata&#8217; nella citt\u00e0 dei bruzi.<\/p>\n<p>&nbsp;<\/p>\n\n","protected":false},"excerpt":{"rendered":"<p>Raffiche di multe per i residenti, trenta nella sola giornata di mercoled\u00ec, a causa di comunicazioni errate da parte del Comune. Poche decine di parcheggi gratuiti per circa cinquecento automobili<\/p>\n","protected":false},"author":18,"featured_media":97986,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[42],"tags":[],"class_list":["post-97985","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cosenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/97985","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=97985"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/97985\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/97986"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=97985"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=97985"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=97985"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}