{"id":98014,"date":"2018-09-09T08:00:31","date_gmt":"2018-09-09T06:00:31","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/ostacoli-quotidiani-e-il-miraggio-di-un-tramonto\/"},"modified":"2023-01-16T18:59:00","modified_gmt":"2023-01-16T17:59:00","slug":"236373-ostacoli-quotidiani-e-il-miraggio-di-un-tramonto","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/236373-ostacoli-quotidiani-e-il-miraggio-di-un-tramonto\/","title":{"rendered":"Ostacoli quotidiani e il miraggio di un tramonto"},"content":{"rendered":"<h4>Ogni giorno, gi\u00e0 fin dal primo momento in cui ci alziamo dal letto ci troviamo a dover compiere una serie di azioni che facciamo meccanicamente, senza partecipazione e, soprattutto, con la sensazione di non trarne nessun effetto benefico a livello psichico.<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>Azioni che, nel libro mastro della nostra esistenza, non le riporteremmo mai nella colonna delle <strong>entrate<\/strong>, ma solo in quella delle <strong>uscite<\/strong>. Spesso le avvertiamo come delle costrizioni, non messe in atto da parte di qualcuno, ma legate alle nostre esigenze fisiologiche primarie, delle quali non possiamo fare a meno, e che sono comunque capaci di sottrarci del tempo prezioso, che dedicheremmo volentieri ad altro.<br \/>\n<strong>Tra queste azioni ripetitive<\/strong>, che facciamo non appena ci svegliamo, rientra anche il <strong>controllo dei messaggi sullo smartphone<\/strong>, quello delle <strong>mail<\/strong> sulla posta elettronica,<strong> o quello dei post su FB<\/strong>. Questa operazione, fatta inizialmente con entusiasmo, sotto la spinta della nostra curiosit\u00e0, a volte, si rivela come qualcosa di estremamente fastidioso, come ad esempio quando ci sentiamo costretti a rispondere a messaggi che non ci interessano.<\/p>\n<p>Appena ci troviamo per strada poi, subiamo una sorta di aggressione, che proviene da pi\u00f9 parti. Da parte di un intreccio confuso di notizie, a volte anche molto tragiche, che apprendiamo dalla radio, o da una prima sommaria lettura del quotidiano appena acquistato. Da parte di manifesti pubblicitari che, con le loro enormi dimensioni e le loro immagini seducenti, sembrano volerci piegare a tutti i costi alla loro volont\u00e0, che \u00e8 quella di indurci all\u2019acquisto di questo o quel prodotto. Da parte delle intemperanze verbali delle persone incontrate casualmente per strada o per motivi di lavoro. Da parte dei nostri pensieri rivolti alle varie <strong>ingiustizie<\/strong> ed ai vari <strong>soprusi<\/strong> che ogni giorno siamo costretti a subire (per alcune persone, stranamente, anche da quelli rivolti alle ingiustizie ed ai soprusi che capitano agli altri) e dalla relativa ricerca delle strategie da mettere in atto per non soccombere in quella che si configura come una vera e propria giungla.<\/p>\n<p>&nbsp;<\/p>\n<p>Una <strong>giungla fatta di richieste di pagamenti<\/strong>, a volte anche non dovuti, di veri e propri assalti da parte di compagnie telefoniche, di luce, di gas, con proposte di cambi di gestore, con offerte tanto strabilianti quanto complesse e difficili da capire, di \u201capp\u201d da scaricare, di siti ai quali \u201cbisogna\u201discriversi, per non rischiare di ritrovarsi esclusi dal civile consorzio umano. Da parte della <strong>banca<\/strong>, della nostra banca, quella che fa di tutto per renderci difficile anche un semplice prelievo di soldi (ovviamente nostri), con ricorrenti fuori-servizio del bancomat, quella che, con l\u2019invio di pagine e pagine di modifiche unilaterali di contratti, con scritte microscopiche, genera in noi ogni sorta di preoccupazione per i nostri risparmi. Da parte delle <strong>noiose incombenze<\/strong>, come la manutenzione della macchina, il rinnovo del bollo e dell\u2019assicurazione, la riparazione della lavatrice, o la partecipazione ad una di quelle estenuanti riunioni di condominio. Se tutto questo poi non dovesse bastare, ci lasciamo stressare da <strong>discussioni su argomenti divisivi<\/strong> (migranti, azioni del governo), o da nostre masturbazioni cerebrali.<\/p>\n<p>E\u2019 un <strong>percorso quotidiano irto di ostacoli<\/strong> che finisce inevitabilmente per trasmetterci malumore, che si accresce ulteriormente se abbiamo la sventura di non avere un lavoro che ci gratifica (o peggio ancora, di non averlo affatto), o di avere nel cuore l\u2019angoscia legata a qualche problema grave di salute, personale o di un nostro familiare.<\/p>\n<p>Questo malumore, che \u00e8 alimentato anche dalla sensazione che tutti questi ostacoli ci facciano perdere del tempo prezioso, ci spinge alla ricerca di un momento in cui possiamo <strong>rilassarci<\/strong>. D\u2019estate, per molti di noi un momento magico, in cui vorremmo fare tutte le cose che ci piacciono, perch\u00e9 tutto ci appare in una luce migliore, \u00e8 quell\u2019intervallo di tempo che prelude alla scomparsa del sole: il <strong>tramonto. <\/strong><\/p>\n<p>Concentrare per\u00f2 tutte le nostre aspettative su quel breve periodo ci fa correre il rischio di restare delusi qualora esse non dovessero avverarsi. Un\u2019utile alternativa potrebbe essere, dopo aver rallentato la nostra corsa, quella di provare a rendere speciale ogni nostra azione quotidiana, anche quella pi\u00f9 ripetitiva e quella apparentemente pi\u00f9 insignificante, mettendo in campo un solo elemento: la nostra partecipazione attiva. Tenendo presente che ogni momento della nostra vita \u00e8 un momento speciale anche gi\u00e0 per il solo fatto che lo possiamo vivere, considerato che, purtroppo, non a tutti \u00e8 concesso il privilegio di poterlo fare fino in fondo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ogni giorno, gi\u00e0 fin dal primo momento in cui ci alziamo dal letto ci troviamo a dover compiere una serie di azioni che facciamo meccanicamente, senza partecipazione e, soprattutto, con la sensazione di non trarne nessun effetto benefico a livello psichico.<\/p>\n","protected":false},"author":31,"featured_media":98015,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[40],"tags":[],"class_list":["post-98014","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura-spettacolo"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/98014","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/31"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=98014"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/98014\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/98015"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=98014"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=98014"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=98014"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}