{"id":9812,"date":"2012-12-17T13:30:31","date_gmt":"2012-12-17T12:30:31","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=9812"},"modified":"2023-01-17T13:42:57","modified_gmt":"2023-01-17T12:42:57","slug":"4375-operazione-nucleo-tutela-patrimonio-culturale","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/4375-operazione-nucleo-tutela-patrimonio-culturale\/","title":{"rendered":"Operazione Nucleo tutela patrimonio culturale"},"content":{"rendered":"<p><strong>NAPOLI<\/strong> &#8211; C&#8217;e&#8217; anche una tela del &#8216;600 raffigurante Gesu&#8217; crocifisso, attribuibile a Mattia Preti,<\/p>\n<p>  <!--more-->  <\/p>\n<p>tra i 95 dipinti sequestrati in diverse operazioni al Centro-Sud dal Nucleo tutela patrimonio culturale dei carabinieri al termine di indagini volte a contrastare il traffico illecito di opere d&#8217;arte rubate. Il valore complessivo dei quadri recuperati si aggira intorno ai 2 milioni di euro. L&#8217;operazione nasce da un controllo effettuato dai militari dell&#8217;Unita&#8217; specializzata dell&#8217;Arma in un negozio di antiquariato del centro storico del capoluogo campano.<\/p>\n<p>Dopo aver comparato le foto dei dipinti di maggior valore con le immagini presenti nella banca dati dei Beni culturali illecitamente sottratti, e&#8217; emerso che due di essi erano stati rubati nelle Marche. Si tratta di un dipinto del &#8216;600 trafugato dalla chiesa del Mengaccio di Mondolfo (PU) e di uno del &#8216;700 rubato dalla chiesa delle Selve dell&#8217;Alta Cesenate di Urbino. Poi sono state individuate le altre tele sottratte da chiese e abitazioni della Campania, dell&#8217;Umbria, delle Marche e del Lazio. &#8220;L&#8217;operazione piu&#8217; importante &#8211; spiega il colonnello Luigi Cortellessa,&nbsp; vicecomandante del Nucleo &#8211; e&#8217; stata effettuata in casa di un 63enne residente a Pescara e gia&#8217; noto alle forze dell&#8217;ordine, che e&#8217; stato denunciato. Nell&#8217;appartamento era concentrata una grande quantita&#8217; di opere che sarebbero state vendute in breve tempo. Siamo arrivati giusto in tempo&#8221;. Tra i dipinti sequestrati, rubati nel corso degli ultimi 22 anni e generalmente in buono stato di conservazione, spiccano il ritratto raffigurante &#8216;Le tre Marie al sepolcro&#8217;, di autore ignoto; la &#8216;Madonna Contestabile&#8217; dell&#8217;800, copia dell&#8217;opera di Raffaello, e la &#8216;Madonna con Bambino&#8217; del &#8216;500 (copia da Mantegna), anche questi di autore ignoto e rubati in un&#8217;abitazione di Perugia. &#8220;Grazie all&#8217;attivita&#8217; preventiva di controllo del territorio &#8211; sottolinea Cortellessa &#8211; e all&#8217;importante quantita&#8217; di informazioni contenute nella banca dati, siamo riusciti a ridurre sensibilmente negli ultimi i furti, azzerandoli nel 2011 per quanto riguarda le opere d&#8217;arte custodite nei musei statali&#8221;.<\/p>\n<p>(Fonte AGI)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>NAPOLI &#8211; C&#8217;e&#8217; anche una tela del &#8216;600 raffigurante Gesu&#8217; crocifisso, attribuibile a Mattia Preti,<\/p>\n","protected":false},"author":22,"featured_media":9813,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,16],"tags":[],"class_list":["post-9812","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-italia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/9812","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=9812"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/9812\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/9813"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=9812"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=9812"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=9812"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}