{"id":9824,"date":"2012-12-17T14:33:20","date_gmt":"2012-12-17T13:33:20","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=9824"},"modified":"2023-01-17T13:42:58","modified_gmt":"2023-01-17T12:42:58","slug":"4381-unical-convegno-sulla-farmacia-italiana","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/4381-unical-convegno-sulla-farmacia-italiana\/","title":{"rendered":"Unical, convegno sulla Farmacia italiana"},"content":{"rendered":"<p><strong>RENDE<\/strong> &#8211; Con il convegno &#8220;La Farmacia Italiana: presente e futuro nella continuit\u00e0 di una tradizione professionale&#8221; hanno preso il via gli appuntamenti previsti nell&#8217;ambito dei<\/p>\n<p>  <!--more-->  <\/p>\n<p>festeggiamenti per i vent&#8217;anni della Facolt\u00e0 di Farmacia e Scienze della Nutrizione e della Salute dell&#8217;UniCal. Non a caso il convegno s&#8217;\u00e8 svolto nell&#8217;aula Circolare del Polifunzionale, il nucleo pi\u00f9 antico dell&#8217;Universit\u00e0 della Calabria, dove due decenni fa veniva inaugurato il primo corso di laurea della Facolt\u00e0.<\/p>\n<p>&lt;&lt;Un evento, quello di oggi, \u2013 ha commentato il Preside della Facolt\u00e0 (oggi Dipartimento n.d.c.), Prof. Sebastiano And\u00f2 \u2013 che ha un grande valore simbolico costituendo una sorta di ponte tra il passato ed il futuro&gt;&gt;. And\u00f2 ha tracciato un articolato excursus delle principali tappe della Facolt\u00e0 pi\u00f9 giovane dell&#8217;Universit\u00e0 della Calabria. &lt;&lt;Grazie a tante persone che hanno collaborato \u2013 ha spiegato \u2013 abbiamo dato vita ad una realt\u00e0 prestigiosa che produce ricerca di qualit\u00e0 e didattica di ottimo livello. Gli obiettivi da perseguire sono adesso legati ad un nuovo concetto di polo tecnologico sanitario che consenta a questa struttura di essere pienamente al servizio del territorio regionale&gt;&gt;. Riferendosi, poi, agli argomenti del convegno, il Prof.Sebastiano And\u00f2, ha evidenziato l&#8217;importanza della figura del farmacista &lt;&lt;Che deve &#8211; ha chiosato \u2013 riguadagnare centralit\u00e0 nel sistema sanitario nazionale &gt;&gt;.<\/p>\n<p>Al convegno ha portato i saluti anche il rettore, Prof. Giovanni Latorre, che ha sottolineato l&#8217;importanza della Facolt\u00e0 di Farmacia non solo nel panorama universitario calabrese, ma come &lt;&lt;utilissimo presidio di ricerca applicata e fucina di ricercatori&gt;&gt;. Il rettore, complimentandosi con quanti hanno reso possibile la straordinaria crescita della Facolt\u00e0, ha concluso l&#8217;intervento augurando il raggiungimento di traguardi ancora pi\u00f9 ambiziosi. L\u2019appuntamento, che \u00e8 stato moderato da Isabella Mezza, conduttrice di &#8220;Salute in Forma&#8221; del Tg3, ha permesso d&#8217;interfacciare il mondo accademico con quello degli Ordini professionali e delle istituzioni pubbliche.<\/p>\n<p>Nell&#8217;occasione sono state conferite targhe e medaglie ricordo a illustri docenti e professionisti che hanno contribuito all&#8217;avvio e allo sviluppo della Facolt\u00e0. La seconda iniziativa in programma per il ventennale della Facolt\u00e0 \u00e8 fissata per Nazionale sul tema: &#8220;L&#8217;Universit\u00e0 e la Formazione in Sanit\u00e0: strategie per il futuro&#8221; durante il quale si confronteranno figure notabili del mondo accademico, delle istituzioni pubbliche e della politica. Seguiranno altre due iniziative convegnistiche la prima delle quali si svolger\u00e0 l&#8217;8 Aprile e avr\u00e0<\/p>\n<p>come tema: &#8220;Farmaci e Prodotti per la salute: nuove prospettive nella ricerca traslazionale&#8221;. Il giorno seguente, il 9 Aprile, saranno conferite le Lauree Magistralis honoris causa in&#8221; Scienza della Nutrizione&#8221; alla dott.ssa Vandana Shiva, e al prof Graziano da Silva, Direttore Generale della FAO.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>RENDE &#8211; Con il convegno &#8220;La Farmacia Italiana: presente e futuro nella continuit\u00e0 di una tradizione professionale&#8221; hanno preso il via gli appuntamenti previsti nell&#8217;ambito dei<\/p>\n","protected":false},"author":22,"featured_media":9825,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,563,44],"tags":[],"class_list":["post-9824","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-area-urbana","category-rende"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/9824","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=9824"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/9824\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/9825"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=9824"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=9824"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=9824"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}