{"id":98539,"date":"2018-09-19T16:51:31","date_gmt":"2018-09-19T14:51:31","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/rende-new-restyling-per-roges-al-via-i-lavori-nella-zona-vecchia\/"},"modified":"2023-01-16T18:59:35","modified_gmt":"2023-01-16T17:59:35","slug":"248170-rende-new-restyling-per-roges-al-via-i-lavori-nella-zona-vecchia","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/248170-rende-new-restyling-per-roges-al-via-i-lavori-nella-zona-vecchia\/","title":{"rendered":"Rende, new restyling per Roges: al via i lavori nella zona vecchia"},"content":{"rendered":"<h4>Prende corpo il progetto di riqualificazione avviato a Roges. Iniziata l\u2019opera di demolizione dei caseggiati abbandonati da anni su via Bari<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-248172 alignleft\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2018\/09\/via-bari-ok-1-373x280.jpg\" alt=\"\" width=\"373\" height=\"280\" title=\"\">RENDE (CS) &#8211; Nato da una sinergia tra Pubblico e privato, l\u2019intervento \u00e8 parte integrante di un Piano di Progetto Unitario (P.P.U.) Il Comune di Rende in collaborazione con la ditta Dimora Srl che eseguir\u00e0 l\u2019opera daranno un nuovo volto al quartiere, attraverso una serie di interventi che vanno dalla realizzazione di un fabbricato residenziale, destinato ad abitazioni, uffici e attivit\u00e0 commerciali, alla creazione di nuovi spazi comuni pensati per grandi e piccoli fino all\u2019allargamento dell\u2019arteria stradale, creazione di 30 posti auto ad uso pubblico, realizzazione marciapiedi con rampe per persone con disabilit\u00e0, implementazione dell\u2019illuminazione pubblica.\u00a0\u00a0 Nell\u2019arco dei prossimi 24 mesi saranno consegnati tutti i lavori. Il progetto \u00e8 stato concepito rispettando la natura del luogo. All\u2019interno della nuova piazza, sar\u00e0 posizionata la storica fontanella, \u00a0simbolo da tantissimi anni della comunit\u00e0. Massima attenzione sar\u00e0 data inoltre al verde e alle aree gioco e di passaggio che saranno concepite per essere accessibili anche alle persone con ridotta mobilit\u00e0.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Prende corpo il progetto di riqualificazione avviato a Roges. Iniziata l\u2019opera di demolizione dei caseggiati abbandonati da anni su via Bari<\/p>\n","protected":false},"author":37,"featured_media":98540,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[44],"tags":[],"class_list":["post-98539","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-rende"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/98539","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/37"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=98539"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/98539\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/98540"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=98539"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=98539"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=98539"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}