{"id":98594,"date":"2018-09-20T17:00:30","date_gmt":"2018-09-20T15:00:30","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/una-pista-ciclopedonale-per-valorizzare-il-ponte-di-campagnano\/"},"modified":"2023-01-16T18:59:38","modified_gmt":"2023-01-16T17:59:38","slug":"248326-una-pista-ciclopedonale-per-valorizzare-il-ponte-di-campagnano","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/248326-una-pista-ciclopedonale-per-valorizzare-il-ponte-di-campagnano\/","title":{"rendered":"Una pista ciclopedonale per valorizzare il ponte di Campagnano"},"content":{"rendered":"<h4>Si \u00e8 tenuto oggi un sopralluogo congiunto tra i tecnici del Comune di Rende e di Cosenza.<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>RENDE (CS) &#8211; Si \u00e8 tenuto questa mattina l\u2019incontro tra le Commissioni Consiliari dei Comuni di Rende e di Cosenza che hanno avviato un sopralluogo congiunto dell\u2019antico ponte in ferro risalente al 1877, rinvenuto nello scorso luglio sotto una folta vegetazione nei pressi di Campagnano. Una scoperta ricca di entusiasmo e di progettazione da parte del primo cittadino di Rende, Marcello Manna e dei tecnici comunali che, sin da subito, hanno inteso valorizzare l\u2019enorme manufatto della vecchia ferrovia che fa parte dell\u2019antica tratta \u201cCosenza-Sibari\u201d e che collega le citt\u00e0 di Rende e Cosenza.<\/p>\n<p>Presenti alle operazioni di sopralluogo il dirigente del settore Lavori Pubblici del Comune di Rende, l\u2019ing. Francesco Minutolo, Francesco Caruso responsabile dell\u2019Assessorato ai Lavori Pubblici del Comune di Cosenza ed una delegazione dei consiglieri dei rispettivi comuni. Il progetto che valorizzer\u00e0 l\u2019antico manufatto, intende creare un collegamento tramite la realizzazione di una lunga pista ciclopedonale: Viale Francesco e Carolina Principe e Viale Giacomo Mancini, nonch\u00e9 le due aree del Parco Nicholas Green e del Parco Robinson, polmoni verdi di Rende.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-248327 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2018\/09\/sopralluogo-ponte-campagnano-.jpg\" alt=\"\" width=\"490\" height=\"423\" title=\"\"><\/p>\n<p>A New York valorizzando antichi ponti, sono riusciti a riqualificare spazi importanti, per la citt\u00e0 di Rende vorrei fare altrettanto\u201d \u00e8 quanto affermato dal sindaco Manna al momento della sorprendente scoperta per troppo tempo rimasta nascosta. Dunque, un progetto ambizioso ed armonico tra le due grandi citt\u00e0 dell\u2019Area Urbana che, con un accordo di programma per opere complementari alla metropolitana di Euro 4.000.000, sta per essere realizzato. Particolarmente entusiasti i consiglieri comunali che hanno partecipato al sopralluogo ed i tecnici coinvolti.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Si \u00e8 tenuto oggi un sopralluogo congiunto tra i tecnici del Comune di Rende e di Cosenza.<\/p>\n","protected":false},"author":22,"featured_media":98595,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[42,44],"tags":[],"class_list":["post-98594","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cosenza","category-rende"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/98594","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=98594"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/98594\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/98595"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=98594"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=98594"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=98594"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}