{"id":98598,"date":"2018-09-21T04:30:52","date_gmt":"2018-09-21T02:30:52","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/usura-ed-estorsione-nei-confronti-di-un-vigile-urbano\/"},"modified":"2023-01-16T18:59:39","modified_gmt":"2023-01-16T17:59:39","slug":"248340-usura-ed-estorsione-nei-confronti-di-un-vigile-urbano","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/248340-usura-ed-estorsione-nei-confronti-di-un-vigile-urbano\/","title":{"rendered":"Usura ed estorsione nei confronti di un vigile urbano di Rende"},"content":{"rendered":"<h4>Doveva pagare gli studi al figlio e chiese un prestito con un tasso usurario di 500 euro al mese. A garanzia del debito da saldare gli fu tolta l&#8217;autovettura<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>RENDE (CS) &#8211; Nuova udienza del processo Citro, i due\u00a0cugini cosentini Roberto e Francesco rispettivamente di\u00a050 e\u00a0 48 anni,\u00a0accusati dei reati di\u00a0\u201cusura aggravata dallo stato di bisogno\u201d ed \u201cestorsione\u201d nei confronti di un vigile urbano che svolge servizio nel comune di Rende. Nell&#8217;ultima udienza era stato sentito come teste la vittima che aveva raccontato come si erano svolti i fatti. Fatti sostenuti da intercettazioni telefoniche per via delle indagini condote dai carabinieri della compagnia di Rende. In particolare la vittima, 49 anni, avrebbe chiesto la somma di 3500 euro per pagare gli studi al figlio e, secondo quanto dichiarato dal 49enne ai carabinieri e secondo quanto rilevato dalle intercettazioni ci sarebbe stata una richiesta di 500 euro al mese come tasso usuraio.\u00a0Una richiesta\u00a0 &#8211; si legge negli atti &#8211; che non avrebbe fatto altro che peggiorare la gi\u00e0 grave situazione economica della vittima, alla quale fu tolta l\u2019autovettura come garanzia per il saldo del debito.<\/p>\n<p>In particolare un carabiniere si \u00e8 finto un cliente per l&#8217;acquisto dell&#8217;autovettura Dacia Duster; militare dell&#8217;Arma che oggi si \u00e8 presentato come teste in aula davanti al collegio giudicante presieduto dal giudice Salvatore Carpino, a latere i giudici Granata e Formoso, per raccontare la trattativa di acquisto con uno dei cugini Citro. Accusa e difesa hanno chiesto l&#8217;acquisizione del verbale del\u00a0 13 marzo 2017, anno la vittima ha deciso di denunciare i fatti alle forze dell&#8217;ordine. Il carabiniere ha dunque risposto alle domande della difesa rappresentata dagli avvocati Antonio Quintieri, Matteo Cristiani, Antonio Ingrosso e Antonio Iaconetti, dell&#8217;accusa rappresentata dal pubblico ministero Giuseppe Cozzolino e della parte civile rappresentata dall&#8217;avvocato Giuliana Ricioppo.<\/p>\n<p>Ha meglio specificato che la trattativa si aggirava intorno agli otto mila euro per quello che aveva fatto intendere al Citro, era la somma di denaro disponibile al momento. Il Citro avrebbe risposto al finto acquirente che per il resto della somma poteva accedere ad un finanziamento perch\u00e8 il veicolo aveva un valore sul mercato di diecimila euro. A conferma sempre Citro avrebbe chiamato ad un amico per chiedere e confermare la quotazione in borsa. Quest&#8217;ultimo avrebbe detto alla vittima, che lamentava un valore economicamente pi\u00f9 alto dell&#8217;auto, di accontentarsi della somma che l&#8217;acquirente aveva proposto per via delle problematiche che c&#8217;erano. \u00abCitro mi diceva di affrettarmi &#8211; sottolinea il carabiniere &#8211; acquirente &#8211; e di pensarci subito perch\u00e8 c&#8217;era gi\u00e0 un altro acquirente. Ho cercato di prendere tempo dicendo che dovevo discuterne con mia moglie e poi far controllare anche la macchina da un meccanico di fiducia. Ma a tal riguardo Citro mi ha spiegato che la macchina era perfetta di meccanica in quanto lui era un meccanico\u00bb.<\/p>\n<p>Il carabiniere spiega ancora che nel capannone c&#8217;era un ragazzo che incontr\u00f2 insieme alla vittima e che disse di attendere mezz&#8217;ora perch\u00e8 Citro era fuori. Subito dopo \u00e8 stato sentito un vigile urbano ormai in pensione, teste della difesa che ha raccontato i rapporti con Citro.<\/p>\n<p>\u00abEro istruttore di polizia municipale in pensione da due anni. Conosco Roberto Citro perch\u00e8 come centralinista lo contattato spesso per gli incidenti. E&#8217; una persona disponibile e gentilissima. Ho una situazione familiare delicata. Avevo bisogno di una macchina e Citro me l&#8217;ha venduta. Fino ad un certo punto l&#8217;ho potuta pagare poi ho spiegato i miei problemi familiari che mi impedivano di continuare a versare le rate e Citro mi ha risposto &#8220;Non ti preoccupare, quando ce li hai me li dai&#8221;. Non mi ha mai chiamato e mai avanzato richieste minatorie\u00bb. Sul collega non ha saputo dare notizie in merito perch\u00e8 ha dichiarato che poco frequentava i suoi colleghi pi\u00f9 giovani. L&#8217;unico episodio che ricorda \u00e8 un debito di una fornitura da 15 euro di benzina che doveva al rifornimento dove erano soliti portare le macchine di servizio.<\/p>\n<p>Ultimo teste dell&#8217;udienza un ex dipendente 22enne, fino al mese di luglio assunto presso l&#8217;officina di Roberto Citro. Ha dichiarato di essere presente al momento in cui Citro consegn\u00f2 il denaro alla vittima. In un primo momento ha dichiarato che non sapeva l&#8217;ammontare ma che vedeva che Citro e la vittima parlavano \u00abNon mi sono avvicinato, vedevo che contavano e poi Citro gli ha detto &#8220;Don\u00e0, ecco i 7 mila euro che mi hai chiesto&#8221;. I soldi sarebbero stati consegnati dalla moglie del Citro in quanto quest&#8217;ultimo avrebbe avuto le mani sporche. Ha dichiarato di essere presente anche alla telefonata tra Citro e la vittima per riavere i soldi dati in prestito &#8220;Don\u00e0 stai rovinando l&#8217;amicizia, ti vado a denunciare. In quel momento era presente anche un altro vigile urbano.<\/p>\n<p>Il teste \u00e8 stato poi incalzato dalla pubblica accusa che ha cambiato parte delle dichiarazioni date in precedenza sempre in aula.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Doveva pagare gli studi al figlio e chiese un prestito con un tasso usurario di 500 euro al mese. A garanzia del debito da saldare gli fu tolta l&#8217;autovettura<\/p>\n","protected":false},"author":40,"featured_media":98599,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[44],"tags":[],"class_list":["post-98598","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-rende"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/98598","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/40"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=98598"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/98598\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/98599"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=98598"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=98598"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=98598"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}