{"id":9864,"date":"2012-12-18T10:55:14","date_gmt":"2012-12-18T09:55:14","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=9864"},"modified":"2023-01-17T13:43:00","modified_gmt":"2023-01-17T12:43:00","slug":"4402-bracconaggio-nei-guai-un-pensionato","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/4402-bracconaggio-nei-guai-un-pensionato\/","title":{"rendered":"Bracconaggio: nei guai un pensionato"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>RENDE &#8211;<\/strong> Attacco alla natura, protetta. Gli agenti della polizia provinciale di Cosenza hanno denunciato un uomo per bracconaggio.<\/p>\n<p>  <!--more-->  <\/p>\n<p style=\"text-align: justify;\">Gli agenti sono riusciti a sorprendere in flagranza di reato, nei pressi dell&#8217;Universit\u00e0, in localit\u00e0 Arcavacata\/Molicelle di Rende, una persona del posto, identificata in B.F. di 73 anni. Il pensionato utilizzava una rete azionata manualmente per il tramite di una lunga fune, e di una gabbia trappola, avvalendosi inoltre di un cardellino ed un verdone per richiamare ed attirare gli uccelli nei congegni che aveva allestito. Gli agenti, fingendosi potenziali acquirenti dei volatili, si sono presentati dall&#8217;indagato, che li ha portati in un magazzino dove deteneva diversi esemplari di cardellino e verdone. Dopo aver identificato l&#8217;uomo, hanno proceduto al sequestro della fauna detenuta, delle attrezzature allestite per la cattura ed alla denuncia del resposabile per il reato di uccellagione e detenzione per la vendita di specie di uccelli particolarmente protette, inserite nell&#8217;allegato II della Convenzione di Berna.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>RENDE &#8211; Attacco alla natura, protetta. Gli agenti della polizia provinciale di Cosenza hanno denunciato un uomo per bracconaggio.<\/p>\n","protected":false},"author":22,"featured_media":9865,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,563,44],"tags":[],"class_list":["post-9864","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-area-urbana","category-rende"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/9864","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=9864"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/9864\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/9865"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=9864"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=9864"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=9864"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}