{"id":98982,"date":"2018-09-28T08:58:23","date_gmt":"2018-09-28T06:58:23","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/bernardo-tradito-dopo-un-anno-e-riportato-in-canile-il-coraggio-di-due-pitbull\/"},"modified":"2023-01-16T19:00:05","modified_gmt":"2023-01-16T18:00:05","slug":"256893-bernardo-tradito-dopo-un-anno-e-riportato-in-canile-il-coraggio-di-due-pitbull","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/256893-bernardo-tradito-dopo-un-anno-e-riportato-in-canile-il-coraggio-di-due-pitbull\/","title":{"rendered":"Bernardo, tradito dopo un anno e riportato in canile. Il coraggio di due pitbull"},"content":{"rendered":"<h4>Anche questa settimana vi presentiamo due storie; la prima \u00e8 quella di un amico peloso da adottare che si trova in canile, e l&#8217;altra \u00e8 quella di uno dei tantissimi casi di cani che, nei loro piccoli gesti, diventano eroi e salvano vite.<\/h4>\n<p><!--more--><\/p>\n<h3><\/h3>\n<h3>Bernardo<\/h3>\n<p>Il piccolo Bernardo dopo 10 mesi in famiglia, \u00e8 stato riportato in canile. Una storia di fedelt\u00e0 dimostrata solo da una parte, come sempre quella dei 4 zampe e non degli esseri umani perch\u00e8 la fedelt\u00e0, quella\u00a0vera, non fa parte dell&#8217;uomo. Bernardo viene adottato quando era cucciolo, quando era era coccoloso ( ma lo \u00e8 ancora), piccolo e carino. Dopo aver vissuto un anno della sua vita al caldo di una casa, in una cuccia comoda, con la sua ciotola pulita e l&#8217;acqua sempre fresca \u00e8 stato tradito.<\/p>\n<p>Dopo un anno infatti, \u00e8 stato restituito in canile senza neanche una lacrima senza neanche guardarsi indietro. Bernardo piangeva come un disperato mentre i suoi padroni salivano in macchina senza batter ciglio. Ora vive in canile e stavolta merita qualcuno che lo ami davvero, che sia fedele per sempre. E&#8217; giovane, bello, simpatico, socievole con tutti gli esseri umani ed i suoi simili.<\/p>\n<h4><span style=\"color: #ff0000;\">ASCOLTA LA RUBRICA<\/span><\/h4>\n<p>[audio_mp3 url=&#8221;https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2018\/09\/quizampa-bernardo.mp3&#8243;]<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-256899 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2018\/09\/bernardo-ok-2.jpg\" alt=\"\" width=\"596\" height=\"423\" title=\"\"><\/p>\n<p>&nbsp;<\/p>\n<h3>\u00a0Pitbull salvano la vita di due bambini<\/h3>\n<p>Slayer e Paco sono due cani eroi. E se il pregiudizio su questa razza \u00e8 molto diffuso e spesso fa paura, la storia che vi raccontiamo \u00e8 quella di due pitbull speciali e neanche la loro famiglia\u00a0poteva immaginare che avrebbero salvato la cosa pi\u00f9 preziosa che avevano: la vita dei loro bambini. Melissa Butt \u00e8 la proprietaria di Slayer. I suoi nipoti, Zayden (4 anni) e Mallory (1 anno e mezzo) stavano giocando con lui e con l\u2019altro cane della famiglia, Paco nel giardino della loro casa in Florida. All\u2019improvviso i due cani hanno per\u00f2 inziiato a ringhiare e ad abbaiare. Sembravano impazziti. I bambini urlavano e piangevano. Cos\u00ec Melissa si \u00e8 precipitata fuori con la paura di trovare i due nipoti tra le fauci dei cani ma la scena l\u2019ha lasciata di stucco: un serpente testa di rame, velenosissimo, era nel suo giardino e Slayer e Pato cercavano di tenerlo lontano dai due bambini.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-256900 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2018\/09\/i-due-pittbull-che-hanno-ucciso-serpente.jpg\" alt=\"\" width=\"733\" height=\"217\" title=\"\"><\/p>\n<p>Arrivata la mamma dei piccoli, Cynthia e suo marito Daniel hanno preso i bambini e li hanno portati dentro casa. Slayer e Pato hanno iniziato a combattere con il serpente che \u00e8 riuscito a mordere Paco a una zampa e Slayer sul muso. A quel punto, incurante della ferita, Slayer si \u00e8 avventato e ha afferrato il serpente con i denti, uccidendolo.<\/p>\n<p>Melissa ha portato i cani di corsa al Pronto Soccorso veterinario e le condizioni di Slayer non erano delle migliori. Il suo muso si era gonfiato dismisura e faceva fatica a respirare.\u00a0Paco stava meglio e Melissa l\u2019ha potuto riportare a casa il giorno dopo ma per Slayer \u00e8 stata dura. Il coraggioso eroe ha continuato per\u00f2 a combattere e alla fine ce l\u2019ha fatta. Si \u00e8 rimesso ed \u00e8 tornato a casa.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\">Se vuoi scriverci per chiedere informazioni sui cani da adottare: <strong>redazione@quicosenza.it<\/strong> (nell\u2019oggetto indicare \u201c<strong>Qui la Zampa<\/strong>\u201c); Se invece vuoi adottare i cani, il giorno delle adozioni in canile a <strong>Donnici<\/strong> \u00e8 il<span style=\"color: #ff0000;\"><strong>\u00a0GIOVEDI&#8217;<\/strong><\/span>. Le adozioni al canile sanitario in contrada Acquafredda di <strong>Mendicino<\/strong> (Cs) invece, si possono effettuare di <span style=\"color: #ff0000;\"><strong>LUNED\u00cc<\/strong> <\/span>dalle 9:30 alle 12:30<\/p>\n<h3 style=\"text-align: center;\">Numeri utili per informazioni e\/o adozioni<\/h3>\n<p style=\"text-align: center;\">Letizia 327 636 2179<br \/>\nMaria Giulia 334 354 2780<br \/>\nTeresa 348 134 3975<br \/>\nNadia 389 051 7756<br \/>\nMaria Francesca 3917348381<\/p>\n<h4 style=\"text-align: center;\"><span style=\"color: #0000ff;\"><a style=\"color: #0000ff;\" href=\"https:\/\/quicosenza.it\/news\/5314\" target=\"_blank\" rel=\"noopener\">\u00a0LEGGI TUTTI GLI ARTICOLI della rubrica &#8220;Qui la Zampa&#8221;<\/a><\/span><\/h4>\n","protected":false},"excerpt":{"rendered":"<p>Anche questa settimana vi presentiamo due storie; la prima \u00e8 quella di un amico peloso da adottare che si trova in canile, e l&#8217;altra \u00e8 quella di uno dei tantissimi casi di cani che, nei loro piccoli gesti, diventano eroi e salvano vite.<\/p>\n","protected":false},"author":22,"featured_media":98983,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[47],"tags":[],"class_list":["post-98982","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-qui-la-zampa"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/98982","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=98982"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/98982\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/98983"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=98982"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=98982"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=98982"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}