{"id":99012,"date":"2018-09-28T15:31:54","date_gmt":"2018-09-28T13:31:54","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/omicidio-augieri-giustizia-per-francesco-lappello-della-famiglia\/"},"modified":"2023-01-16T19:00:06","modified_gmt":"2023-01-16T18:00:06","slug":"257004-omicidio-augieri-giustizia-per-francesco-lappello-della-famiglia","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/257004-omicidio-augieri-giustizia-per-francesco-lappello-della-famiglia\/","title":{"rendered":"Omicidio Augieri, giustizia per Francesco: l&#8217;appello della famiglia"},"content":{"rendered":"<h4>\u00ab\u00c8 passato poco pi\u00f9 di un mese dall&#8217;avvenimento che lo scorso 22 Agosto ha scosso le coscienze di tantissime persone, con risonanza a livello nazionale, per l&#8217;efferatezza del gesto che ha interessato un giovane di soli 23 anni di Cosenza, Francesco Augieri, intervenuto per difendere un amico barbaramente attaccato per futili motivi da una baby gang, armata di coltelli e predisposta a mettere in atto azioni di inaudita ferocia\u00bb<\/h4>\n<p><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p>COSENZA &#8211; A scrivere \u00e8 lo zio di Francesco che grida al muro di omert\u00e0 che avvolge la morte del nipote. \u00abTra le cose che mi hanno pi\u00f9 impressionato nel corso di questo primo mese, a parte naturalmente il fatto di cronaca nera in s\u00e8, \u00e8 stato il muro di omert\u00e0 che si \u00e8 sollevato all&#8217;indomani dell&#8217;assassinio del 22 Agosto.<br \/>\nCome \u00e8 facilmente immaginabile, tutto ci\u00f2 si traduce in un vantaggio a favore di quanti si sono macchiati del crudele omicidio ed ostacola il passo a quanti sono, invece, impegnati nell&#8217;opera di fare luce nei fatti avvenuti in quella tragica notte di sangue, dando un volto agli autori materiali della spietata esecuzione, nel tentativo di dare giustizia alla giovane vittima, immolatasi per difendere un amico.<\/p>\n<p>Credo che, sia i villeggianti presenti sul posto (in gran parte di origine campana) e sia soprattutto la popolazione di Diamante, debbano dare oggi un significato pi\u00f9 concreto all&#8217;attestazione di solidariet\u00e0 e vicinanza manifestata alla famiglia della vittima con la fiaccolata del 25 Agosto scorso (la fiaccola \u00e8 appunto simbolo di luce e di verit\u00e0), rompendo cos\u00ec il muro del silenzio e di omert\u00e0 mediante la collaborazione con i Carabinieri e la Procura di Paola.<br \/>\nAl contrario, continuare a tenere nascosta la verit\u00e0 e non dare il proprio contributo alla sua ricerca (inviando al sottoscritto anche in forma anonima, video, foto o indicazioni utili per risalire agli assassini) significa diventare complici di quella parte della societ\u00e0 che disprezza e calpesta il diritto alla vita di ogni persona, che pu\u00f2 essere nostro figlio, fratello o amico.<br \/>\nIn effetti \u00e8 veramente inquietante (e ci\u00f2 deve far molto riflettere) il dover ammettere che chiunque poteva trovarsi in quella tragica notte di sangue al posto di Francesco, accerchiato da un branco di feroci assassini e senza possibilit\u00e0 di uscirne vivo.<\/p>\n<p>Sono nella condizione di poter collaborare nella ricerca della verit\u00e0 tutti coloro che si sono trovati ad assistere allo svolgimento di quella tragica esecuzione.<br \/>\nPer fare ci\u00f2 non si dovr\u00e0 attendere altro tempo, visto che gli organi di informazione ieri hanno diffuso la notizia della richiesta di scarcerazione fatta al Tribunale della Libert\u00e0 di Catanzaro dai due legali di Francesco Schiattarelli, il diciannovenne napoletano, individuato dalla Procura di Paola come uno degli autori del feroce assassinio di Francesco Augieri.<\/p>\n<p>In aggiunta a quanto sopra argomentato, ritengo che ci sia un&#8217;ulteriore importante motivazione per contribuire alla ricerca della verit\u00e0 (ripeto, anche in forma anonima al sottoscritto , attraverso FB, Messenger, e-mail) che \u00e8 quella di onorare un giovane deceduto prematuramente a soli 23 anni, che ha offerto generosamente la propria vita per difendere un suo amico violentemente attaccato da un branco di feroci malviventi. \u00c8 superfluo sottolineare che ci\u00f2 servir\u00e0 ad evitare che il silenzio e l&#8217;omert\u00e0 della societ\u00e0 civile uccidano Francesco per la seconda volta.<br \/>\nDa zio affranto dal dolore chiedo, infine, a tutti coloro che vogliono GIUSTIZIA PER FRANCESCO di condividere in rete questo appello.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00ab\u00c8 passato poco pi\u00f9 di un mese dall&#8217;avvenimento che lo scorso 22 Agosto ha scosso le coscienze di tantissime persone, con risonanza a livello nazionale, per l&#8217;efferatezza del gesto che ha interessato un giovane di soli 23 anni di Cosenza, Francesco Augieri, intervenuto per difendere un amico barbaramente attaccato per futili motivi da una baby [&hellip;]<\/p>\n","protected":false},"author":21,"featured_media":99013,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[42,28,576],"tags":[],"class_list":["post-99012","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cosenza","category-provincia","category-tirreno"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/99012","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/21"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=99012"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/99012\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/99013"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=99012"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=99012"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=99012"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}