{"id":99068,"date":"2018-10-01T04:37:09","date_gmt":"2018-10-01T02:37:09","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/scalea-scoperti-24-lavoratori-irregolari-coinvolte-due-societa\/"},"modified":"2023-01-16T19:00:10","modified_gmt":"2023-01-16T18:00:10","slug":"257294-scalea-scoperti-24-lavoratori-irregolari-coinvolte-due-societa","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/257294-scalea-scoperti-24-lavoratori-irregolari-coinvolte-due-societa\/","title":{"rendered":"Scalea, scoperti 24 lavoratori irregolari. Coinvolte due societ\u00e0"},"content":{"rendered":"<h4>La Guardia di Finanza di Scalea 24 lavoratori irregolari in quanto impiegati in parte in \u201cnero\u201d ed in parte attraverso l\u2019utilizzo improprio di contratti di appalto di servizi.<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>SCALEA (CS) &#8211; Due societ\u00e0 calabresi nel mirino dei finanzieri di Scalea, che si erano accordate al fine di impiegare manodopera attraverso la stipula un apparente contratto di appalto di servizi che, tuttavia, nascondeva una effettiva somministrazione di lavoro. I lavoratori, <strong>seppur formalmente assunti da una societ\u00e0 di Lamezia Terme<\/strong>, prestavano di fatto <strong>irregolare<\/strong> attivit\u00e0 lavorativa presso un\u2019altra societ\u00e0 dell\u2019Alto Tirreno cosentino, in forza della sottoscrizione di un <strong>\u201cappalto di servizi\u201d<\/strong>: forma contrattuale molto diffusa tra le aziende in quanto consente di snellire le incombenze burocratiche legate all\u2019assunzione e di fruire, al contempo, della prestazione lavorativa del dipendente.<\/p>\n<p>Se, per\u00f2, da un lato questa procedura presenta evidenti vantaggi per l\u2019azienda che usufruisce della manodopera, dall\u2019altro pu\u00f2 prestare il fianco ad <strong>abusi a danno dei lavoratori,<\/strong> quali: il mancato rispetto del minimo salariale, della normativa in materia di sicurezza e salute sui luoghi di lavori, la mercificazione della prestazione lavorativa, etc., a causa della separazione tra la titolarit\u00e0 formale del rapporto di lavoro e l\u2019effettiva fruizione della prestazione.<\/p>\n<p>Ed \u00e8 proprio finalizzata a garantire la massima tutela dei lavoratori ed evitare eventuali usi distorti della particolare forma contrattuale la previsione del legislatore di richiedere espressamente che gli appalti di servizi non si riducano alla mera somministrazione di manodopera, ma prevedano un\u2019opera compiuta, un servizio complesso, mediante l\u2019impiego di organizzazione, mezzi e strumenti di propriet\u00e0 dell\u2019appaltatore; per cui, qualora il cedente la manodopera si limiti a conferire la mera prestazione lavorativa dei suoi dipendenti si \u00e8 in presenza di una mera somministrazione di lavoro che deve essere autorizzata attraverso l\u2019iscrizione della societ\u00e0 ad apposito albo detenuto presso il Ministero del Lavoro.<\/p>\n<p>L\u2019azione ispettiva sviluppata dalla Fiamme Gialle ha consentito di fare emergere chiaramente la <strong>non corrispondenza della forma contrattuale sottoscritta alle caratteristiche previste dalla legge<\/strong>, rivelandosi un caso di somministrazione di lavoro compiuta in maniera abusiva in quanto la societ\u00e0, non essendo iscritta presso l\u2019albo ministeriale, non offriva le dovute garanzie di tutela ai lavoratori. I Finanzieri hanno quindi proceduto alla contestazione nei confronti di entrambe le societ\u00e0 responsabili delle <strong>sanzioni amministrative per \u20ac 145.000.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Guardia di Finanza di Scalea 24 lavoratori irregolari in quanto impiegati in parte in \u201cnero\u201d ed in parte attraverso l\u2019utilizzo improprio di contratti di appalto di servizi.<\/p>\n","protected":false},"author":22,"featured_media":99069,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[28,576],"tags":[],"class_list":["post-99068","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-provincia","category-tirreno"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/99068","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=99068"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/99068\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/99069"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=99068"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=99068"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=99068"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}