{"id":99184,"date":"2018-10-03T07:43:35","date_gmt":"2018-10-03T05:43:35","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/tragico-incidente-tra-lattarico-e-montalto-violento-impatto-tra-due-auto\/"},"modified":"2023-01-16T19:00:19","modified_gmt":"2023-01-16T18:00:19","slug":"257815-tragico-incidente-tra-lattarico-e-montalto-violento-impatto-tra-due-auto","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/257815-tragico-incidente-tra-lattarico-e-montalto-violento-impatto-tra-due-auto\/","title":{"rendered":"Tragico incidente tra Lattarico e Montalto. Un morto e due feriti, tra cui un bimbo"},"content":{"rendered":"<h4>L&#8217;incidente \u00e8 avvenuto stamattina sulla strada provinciale 102 in zona Campo di Fieno, tra Lattarico e Montalto.<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>MONTALTO UFFUGO (CS) &#8211; Ambulanze a sirene spiegate, elisoccorso e vigili del fuoco sul posto questa mattina per un gravissimo incidente stradale avvenuto tra i centri di Lattarico e Pianette di Montalto Uffugo sulla Provinciale 102. Lo scontro ha visto coinvolte due auto, una Fiat Panda vecchio modello e una Fiat Punto. Nell&#8217;impatto <strong>un uomo di 69 anni Angelo Morelli, che viaggiava sulla Panda ha perso la vita<\/strong>, mentre altre due persone,\u00a0<strong>una mamma e il figlio piccolo che era sul seggiolino, <\/strong>sono state soccorse dai sanitari del 118 e <strong>trasportate d&#8217;urgenza in ospedale<\/strong> a Cosenza. Le loro condizioni per\u00f2 non sarebbero gravi. Sul posto i Vigili del fuoco del distaccamento di Rende guidati dal caposquadra Francesco Maddalone e i carabinieri per i rilievi e la gestione della viabilit\u00e0 sul tratto.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-257822 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2018\/10\/incidente-montalto-lattarico-1-440x275.jpg\" alt=\"\" width=\"440\" height=\"275\" title=\"\"><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&#8217;incidente \u00e8 avvenuto stamattina sulla strada provinciale 102 in zona Campo di Fieno, tra Lattarico e Montalto.<\/p>\n","protected":false},"author":22,"featured_media":99185,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[566],"tags":[],"class_list":["post-99184","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-montalto"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/99184","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=99184"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/99184\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/99185"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=99184"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=99184"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=99184"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}