{"id":99260,"date":"2018-10-04T17:05:56","date_gmt":"2018-10-04T15:05:56","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/auto-si-ribalta-quattro-feriti\/"},"modified":"2023-01-16T19:00:24","modified_gmt":"2023-01-16T18:00:24","slug":"258040-auto-si-ribalta-quattro-feriti","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/258040-auto-si-ribalta-quattro-feriti\/","title":{"rendered":"Auto si ribalta, quattro feriti"},"content":{"rendered":"<h4>Incidente nella frazione di Trenta, tra i feriti due minorenni. Sul posto sono intervenuti i sanitari della Misericordia e i vigili del fuoco<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>TRENTA (CS) &#8211; Fortunatamente si potrebbe definire solo un incidente spettacolare perch\u00e8 gli occupanti la vettura, una Matiz, non hanno riportato ferite se non una gran paura. L&#8217;incidente \u00e8 avvenuto nella frazione Schiavonea di Trenta, a Cosenza, nei pressi della pizzeria Paradiso. Probabilmente per via dell&#8217;asfalto viscido, reso tale dalla pioggia, il conducente ha perso il controllo della macchina finendo fuori strada.<\/p>\n<p>L&#8217;auto ha carambolato pi\u00f9 volte fino a terminare la sua corsa in un terreno adiacente la carreggiata. I quattro occupanti, tra cui due minori, sono stati soccorsi nell&#8217;immediato dai sanitari della Misericordia. Sul posto anche i vigili del fuoco del comando provinciale di Cosenza per la messa in sicurezza del mezzo. I feriti a scopo precauzionale sono stati trasportati al Pronto soccorso dell&#8217;Annunziata per accertamenti. Sul posto le forze dell&#8217;ordine per effettuare i rilievi ed accertare le cause all&#8217;origine dell&#8217;incidente<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Incidente nella frazione di Trenta, tra i feriti due minorenni. Sul posto sono intervenuti i sanitari della Misericordia e i vigili del fuoco<\/p>\n","protected":false},"author":40,"featured_media":99261,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[42],"tags":[],"class_list":["post-99260","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cosenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/99260","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/40"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=99260"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/99260\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/99261"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=99260"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=99260"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=99260"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}