{"id":99322,"date":"2018-10-06T04:55:42","date_gmt":"2018-10-06T02:55:42","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/un-ottobre-ricco-di-eventi-per-lassociazione-mammachemamme\/"},"modified":"2023-01-16T19:00:27","modified_gmt":"2023-01-16T18:00:27","slug":"258230-un-ottobre-ricco-di-eventi-per-lassociazione-mammachemamme","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/258230-un-ottobre-ricco-di-eventi-per-lassociazione-mammachemamme\/","title":{"rendered":"Ottobre ricco di eventi per l&#8217;Associazione Mammachemamme"},"content":{"rendered":"<h4>L&#8217;evento di oggi si svolger\u00e0 presso la Cittadella del Volontariato dalle ore 16,30 in poi.<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>COSENZA -In linea con quanto celebra la<strong> SAM 2018<\/strong>, ovvero\u00a0l\u2019allattamento come ricetta universale per pareggiare le condizioni di\u00a0 partenza di tutti e garantire a ciascuno un buon inizio, che migliora il livello di salute, benessere e sopravvivenza di donne e bambine e\u00a0bambini in tutto il mondo, l\u2019associazione MammacheMamme intende\u00a0 veicolare e promuovere una corretta ed indispensabile informazione, un\u00a0 evento strutturato su pi\u00f9 livelli. Durante l\u2019evento sar\u00e0 possibile prendere parte a diverse attivit\u00e0,\u00a0quali: laboratorio esperienziale dedicato alle emozioni della maternit\u00e0 a\u00a0cura del MIPPE \u2013 Movimento Italiano Psicologia Perinatale.\u00a0Proiezione del video lancio \u201cLe Parole che Non Ho Detto\u201d e del\u00a0 video-raccolta delle immagini inviate dalle mamme durante la campagna\u00a0\u201cLe Parole che non ho detto\u201d lanciata da MammacheMamme ad Agosto 2018.<\/p>\n<p><strong>\u201cLa Mia Storia di Allattamento\u201d<\/strong>: lettura di storie di allattamento\u00a0 inviate dalle madri all\u2019ADV Mammachemamme dal 2012 ad oggi. Spazio di accoglienza per le bambine e bambini con azioni mirate alla\u00a0sensibilizzazione sul te-ma dell\u2019allattamento al seno. Sar\u00e0 presente un punto informazioni e sostegno sul babywearing a cura\u00a0della Fascioteca Coccole in fasce e un Family Point per le famiglie.\u00a0L&#8217;evento \u00e8 patrocinato e sostenuto da: Comune di Cosenza, Provincia di\u00a0 Cosenza, Unicef, Ordine degli Psicologi della Calabria, Mippe (Movimento\u00a0Italiano Psicologia Perinatale) e CSV Cosenza e parteciper\u00e0 al Giorno\u00a0Del Dono previsto dal CSV Cosenza.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-258234 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2018\/10\/allattamento-dubbi2.jpg\" alt=\"\" width=\"510\" height=\"290\" title=\"\"><\/p>\n<p>Il <strong>14 ottobre<\/strong> alla Villa Vecchia di Cosenza, Mammachemamme in\u00a0collaborazione con Crescimondo festeggeranno insieme la Festa dei Nonni,\u00a0con l\u2019incontro\/laboratorio dal titolo &#8220;La fabbrica dei nonni 2018&#8221;: una\u00a0appuntamento per i bambini e le bambine della citt\u00e0 per celebrare i\u00a0nonni attraverso giochi, girotondi e musiche della tradizione popolare.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-258235 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2018\/10\/n3.jpeg\" alt=\"\" width=\"600\" height=\"337\" title=\"\"><\/p>\n<p>Concluderanno il<strong> 15 ottobre<\/strong> con l\u2019evento \u201cBabyloss 2018\u201d, presso la Casa\u00a0delle Culture di Cosenza, nella bellissima cornice del centro storico\u00a0della citt\u00e0, nella giornata della consapevolezza sul lutto perinatale. I\u00a0volontari e le volontarie di CiaoLapo Onlus, dell&#8217;Associazione di\u00a0Volontariato Mammachemamme e del GAMA Parole in ConTatto per il quinto\u00a0anno consecutivo a Cosenza saranno presenti per incontrare genitori,\u00a0operatori e tutti coloro vogliano conoscere le nostre attivit\u00e0 e\u00a0ricordare i bambini e le bambine che ci hanno lasciato troppo presto.\u00a0Il pomeriggio si articoler\u00e0 attraverso varie attivit\u00e0 e momentidi\u00a0condivisione, ascolto ed incontro. Durante l\u2019evento sar\u00e0 possibile, inoltre, visitare la Mostra di disegni\u00a0delle bambine e dei bambini dal titolo \u201cUn ponte tra cielo e terra\u201d. Questo evento \u00e8 in collaborazione con Ciao Lapo Onlus e patrocinato e\u00a0sostenuto da istituzioni, enti ed associazioni sensibili ai temi\u00a0trattati: Comune di Cosenza, Provincia di Cosenza, Unicef, Ordine degli\u00a0Psicologi della Calabria, Ordine Provinciale Medici Chirurghi E Degli\u00a0Odontoiatri di Cosenza, Collegio Provinciale Delle Ostetriche Cosenza e\u00a0CSV Cosenza.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-258236 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2018\/10\/gettyimages-532426580-1521560799.jpg\" alt=\"\" width=\"480\" height=\"241\" title=\"\"><\/p>\n<p><strong>L\u2019ottobre di Mammachemamme \u00e8 un mese che profuma di latte materno,\u00a0cultura del rispetto, di radici e famiglia e di consapevolezza.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&#8217;evento di oggi si svolger\u00e0 presso la Cittadella del Volontariato dalle ore 16,30 in poi.<\/p>\n","protected":false},"author":20,"featured_media":99323,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[40],"tags":[],"class_list":["post-99322","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura-spettacolo"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/99322","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/20"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=99322"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/99322\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/99323"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=99322"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=99322"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=99322"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}