{"id":9940,"date":"2012-12-19T09:31:48","date_gmt":"2012-12-19T08:31:48","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=9940"},"modified":"2023-01-17T13:43:05","modified_gmt":"2023-01-17T12:43:05","slug":"4440-arte-azzinari-a-washington","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/4440-arte-azzinari-a-washington\/","title":{"rendered":"Arte: Azzinari a Washington"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>CATANZARO<\/strong> &#8211; Per la cerimonia di apertura dell&#8217;Anno della Cultura Italiana in America 2013 a Washington, con il Ministro Giulio Terzi ha<\/p>\n<p>  <!--more-->  <\/p>\n<p style=\"text-align: justify;\">partecipato anche Franco Azzinari, uno dei pochi artisti viventi inseriti nel palinsesto del &#8216;Year of Italian Culture&#8217; America 2013. Il pittore calabrese parteciper\u00e0 al programma con la mostra &#8220;Looking for Hemingway&#8221; che verra&#8217; inaugurata il 20 maggio 2013 a Boston e rester\u00e0 aperta fino al 28 giugno. La mostra \u00e8 stata inoltre richiesta a Philadelphia e in Virginia. (Fonte ANSA)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>CATANZARO &#8211; Per la cerimonia di apertura dell&#8217;Anno della Cultura Italiana in America 2013 a Washington, con il Ministro Giulio Terzi ha<\/p>\n","protected":false},"author":22,"featured_media":9941,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,17],"tags":[],"class_list":["post-9940","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/9940","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=9940"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/9940\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/9941"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=9940"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=9940"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=9940"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}