{"id":9946,"date":"2012-12-19T10:10:14","date_gmt":"2012-12-19T09:10:14","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=9946"},"modified":"2023-01-17T13:43:05","modified_gmt":"2023-01-17T12:43:05","slug":"4444-da-regione-fondi-per-microzonizzazione-sismica","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/4444-da-regione-fondi-per-microzonizzazione-sismica\/","title":{"rendered":"Da Regione fondi per microzonizzazione sismica"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>MORANO CALABRO (CS)<\/strong> &#8211; Dalla Regione Calabria, attraverso l&#8217; Assessorato ai Lavori pubblici e Infrastrutture, arrivano i fondi al Comune di Morano Calabro per la microzonizzazione<\/p>\n<p>  <!--more-->  <\/p>\n<p style=\"text-align: justify;\">sismica. A darne notizia l&#8217;assessore Giannatale Tramaglino il quale nel divulgare i contenuti della comunicazione pervenuta al protocollo dell&#8217;Ente lunedi&#8217; 17 dicembre scorso, pone l&#8217;accento &#8220;sulle diverse iniziative intraprese dall&#8217;esecutivo locale nell&#8217;ambito delle politiche territoriali e nella fattispecie delle problematiche attinenti all&#8217;interminabile sequenza sismica che colpisce il Pollino ormai da piu&#8217; di tre anni&#8221;. L&#8217;importo complessivo del contributo concesso dall&#8217;organismo regionale ammonta ad 13.499,85 euro e sara&#8217; impiegato &#8211; spiega Tramaglino &#8211; per l&#8217;esecuzione di indagini specifiche, volte a definire l&#8217;entita&#8217; del rischio effettivo suddiviso per microaree individuate nel centro urbano&#8221;. (Fonte AGI)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>MORANO CALABRO (CS) &#8211; Dalla Regione Calabria, attraverso l&#8217; Assessorato ai Lavori pubblici e Infrastrutture, arrivano i fondi al Comune di Morano Calabro per la microzonizzazione<\/p>\n","protected":false},"author":22,"featured_media":9947,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,18],"tags":[],"class_list":["post-9946","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-dai-comuni"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/9946","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=9946"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/9946\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/9947"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=9946"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=9946"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=9946"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}