{"id":99523,"date":"2018-10-10T14:08:47","date_gmt":"2018-10-10T12:08:47","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/pedopornografia-e-violenza-sessuale-giudice-condannato-a-sette-anni-di-reclusione\/"},"modified":"2023-01-16T19:00:41","modified_gmt":"2023-01-16T18:00:41","slug":"258964-pedopornografia-e-violenza-sessuale-giudice-condannato-a-sette-anni-di-reclusione","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/258964-pedopornografia-e-violenza-sessuale-giudice-condannato-a-sette-anni-di-reclusione\/","title":{"rendered":"Pedopornografia e violenza sessuale, giudice condannato a sette anni di reclusione"},"content":{"rendered":"<h4>Il magistrato, attualmente sospeso dalle proprie funzioni, avrebbe abusato di un&#8217;adolescente di cui ha diffuso in rete le immagini, mentre questa dormiva<\/h4>\n<p><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p>MESSINA &#8211; \u00a0\u201cDi che et\u00e0 le preferisci?\u201d. \u201cGuarda, io non ho limiti di et\u00e0. Mi intrigano anche piccolissime: sono pi\u00f9 malleabili\u201d. \u201cIo max 13\u201d. Queste le frasi captate nel corso di un&#8217;inchiesta partita dalla Polizia Postale di Trento focalizzata su una rete di pedofili aveva travolto alla fine del 2017 anche un magistrato di 58 anni oggi condannato in primo grado. Il gup di Messina, Salvatore Mastroeni, ha condannato a 7 anni e 100 mila euro di multa l&#8217;ex giudice Gaetano Maria Amato che doveva rispondere delle pesanti accuse di produzione e diffusione di materiale pedopornografico e violenza sessuale. Il togato indagato nell&#8217;ambito dell&#8217;operazione Black Shadow, che nel frattempo e&#8217; stato sospeso dalle funzioni, era giudice presso la sezione penale della Corte d&#8217;appello di Reggio Calabria. Amato era finito in un&#8217;inchiesta su una rete nazionale di scambio di materiale dal contenuto pedopornografico creata da un 38enne di Bolzano. I pubblici ministeri Giovannella Scaminaci e Claudio Conte avevano chiesto 9 anni e 6 mesi nel giudizio che si e&#8217; svolto con il rito abbreviato. Secondo l&#8217;accusa, Amato, avrebbe <strong>diffuso in rete le immagini di due ragazze minori di 16 anni da lui fotografate mentre erano completamente nude e scaricato da internet materiale pornografico con fotografie di adolescent<\/strong>i (in totale circa 40 foto), inoltre avrebbe partecipato a chat con altre persone interessate allo scambio di foto.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Infine la procura gli contesta anche di aver palpeggiato una delle adolescenti riprese. Sarebbe accaduto mentre la ragazza dormiva. Il giudice dopo aver trascorso due mesi in carcere \u00e8 stato tradotto agli arresti domiciliari. Nella chat criptata di Skype in cui appassionati di pedopornografia si incontravano per scambiare foto di bimbi in atti sessuali contava 48 iscritti. Tra i dieci arrestati di et\u00e0 compresa tra i 39 e i 70 anni appare anche un infermiere trentino di 46 anni C. F. , due insegnanti delle scuole medie, un allenatore di calcio giovanile e un 53enne di Rimini nella cui abitazione sarebbe stato anche trovato un dossier di 40 pagine interamente dedicato a Yara Gambirasio. <strong>I minori coinvolti, ritratti nudi in pose esplicite e anche durante gli abusi, avevano et\u00e0 presunte dai 3 ai 12 anni.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il magistrato, attualmente sospeso dalle proprie funzioni, avrebbe abusato di un&#8217;adolescente di cui ha diffuso in rete le immagini, mentre questa dormiva<\/p>\n","protected":false},"author":22,"featured_media":99524,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[16],"tags":[],"class_list":["post-99523","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-italia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/99523","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=99523"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/99523\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/99524"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=99523"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=99523"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=99523"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}