{"id":99639,"date":"2018-10-13T06:40:19","date_gmt":"2018-10-13T04:40:19","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/meteo-cosenza-instabile-con-locali-piovaschi-e-temporali-continua-il-clima-mite-e-umido\/"},"modified":"2023-01-16T19:00:49","modified_gmt":"2023-01-16T18:00:49","slug":"259294-meteo-cosenza-instabile-con-locali-piovaschi-e-temporali-continua-il-clima-mite-e-umido","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/259294-meteo-cosenza-instabile-con-locali-piovaschi-e-temporali-continua-il-clima-mite-e-umido\/","title":{"rendered":"Meteo Cosenza, instabile con locali piovaschi e temporali. Continua il clima mite e umido"},"content":{"rendered":"<h4><span style=\"color: #000000;\">Continuano i disturbi provocati dal vortice presente tra la Sicilia e la Tunisia con piogge e temporali che si intensificheranno sui versanti jonici soprattutto domenica e luned\u00ec in un contesto climatico mite e umido<\/span><!--more--><\/h4>\n<p><span style=\"color: #ffffff;\">.<\/span><br \/>\n<span style=\"color: #000000;\">COSENZA &#8211; La Calabria si trova proprio al centro tra <strong>due campi di alta pressione<\/strong>. Quello <strong>subtropicale<\/strong>, che dalla Spagna ha raggiunto le regioni del centro\/nord e si \u00e8 collegato e quello presente oramai da oltre una settimana su tutto l&#8217;est Europa e che sta garantendo clima stabile, soleggiato con temperature ben al di sopra della media del periodo. <strong>Caldo e clima umido che in questi giorni<\/strong> non riguarda solo il Mediterraneo, ma \u00e8 arrivato sin verso la Germania e pi\u00f9 su a lambire persino la Scandinavia con temperature massimo vicine se non superiori ai 25 gradi. <\/span><\/p>\n<p><span style=\"color: #000000;\">Nel frattempo il <strong>vortice ciclonico<\/strong> che ha colpito duramente prima le Baleari e poi la Sardegna \u00e8 sfilato a sud e in questo momento, seppur indebolito, lo ritroviamo attivo tra la Sicilia e la Tunisia dove non mancano rovesci e temporali. Proprio il sud peninsulare, quindi anche la Calabria, <strong>risentir\u00e0 per tutto il fine settimana di questa circolazione instabile<\/strong> che sar\u00e0 alimentata da masse di aria umida. E se oggi sar\u00e0 la Sicilia la regione pi\u00f9 colpita da acquazzoni e temporali,\u00a0<strong>domenica e luned\u00ec piogge e rovesci si intensificheranno anche sulla Calabria<\/strong>\u00a0interessando sopratutto i versati ionici e la pi\u00f9 meridionale della regione con le temperature che continueranno a rimanere ben al di sopra della media.<\/span><\/p>\n<h4><span style=\"color: #ff0000;\">Per QuiCosenza le previsioni meteo della prossima settimana a cura del Colonnello Mario Giuliacci<\/span><\/h4>\n<p><iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/syHWGAMKmKE?rel=0&amp;controls=0\" width=\"640\" height=\"360\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Continuano i disturbi provocati dal vortice presente tra la Sicilia e la Tunisia con piogge e temporali che si intensificheranno sui versanti jonici soprattutto domenica e luned\u00ec in un contesto climatico mite e umido<\/p>\n","protected":false},"author":22,"featured_media":99640,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[571,221],"tags":[],"class_list":["post-99639","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-in-evidenza","category-previsioni-meteo-per-cosenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/99639","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=99639"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/99639\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/99640"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=99639"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=99639"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=99639"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}