{"id":99658,"date":"2018-10-12T18:07:16","date_gmt":"2018-10-12T16:07:16","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/studentessa-calabrese-va-alluniversita-con-la-bimba-e-viene-allontanata\/"},"modified":"2023-01-16T19:00:49","modified_gmt":"2023-01-16T18:00:49","slug":"259347-studentessa-calabrese-va-alluniversita-con-la-bimba-e-viene-allontanata","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/259347-studentessa-calabrese-va-alluniversita-con-la-bimba-e-viene-allontanata\/","title":{"rendered":"Studentessa calabrese all&#8217;Universit\u00e0 con la bimba viene allontanata"},"content":{"rendered":"<h4>La professoressa che teneva la lezione ha invitato la giovane mamma ad andare via perch\u00e9 la bimba, anche se dormiva, avrebbe potuto disturbare<\/h4>\n<p><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p>L&#8217;AQUILA &#8211; Paradossale episodio di &#8216;razzismo&#8217; contro i neonati nell&#8217;Universit\u00e0 dell&#8217;Aquila. Una mamma calabrese di 24 anni iscritta al corso di Scienze della Formazione Primaria, titolo di studio valido per l&#8217;accesso all&#8217;insegnamento nelle scuole materne e primarie, \u00e8 stata invitata ieri mattina ad uscire dall&#8217;aula perch\u00e9 aveva portato con s\u00e9 sua figlia. La bimba di appena 4 mesi dormiva nel passeggino e nonostante la studentessa abbia fatto notare ci\u00f2 le \u00e8 stato negato di seguire la lezione insieme ai suoi colleghi. La ragazza, originaria di Zambrone, ha quindi inteso allertare il rettorato e la presidenza di facolt\u00e0 facendo presente il comportamento discriminatorio della docente che le avrebbe, di fatto, impedito di godere del diritto allo studio solo perch\u00e9 non aveva modo di affidare ad altri la neonata. In una lettera ha spiegato che le <strong>&#8220;sembra incredibile essere insultati di fronte a centinaia di ragazzi solo perch\u00e9 si ha la colpa di essere una giovane mamma che vuole laurearsi&#8221;.\u00a0<\/strong>La rettrice Paola Inverardi, dopo essere stata informata insieme al Presidente di Corso e al Direttore di Dipartimento, \u00e8 subito intervenuta ed ha fatto s\u00ec che la ragazza tornasse in aula dove ha ricevuto le scuse &#8216;forzate&#8217; della professoressa che le ha concesso di restare a seguire lezione. La ventiquattrenne ha per\u00f2 spiegato che essendosi creata una situazione di tensione dopo qualche minuto \u00e8 andata via amareggiata &#8220;perch\u00e9 a quel punto era ormai notevole il disagio&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La professoressa che teneva la lezione ha invitato la giovane mamma ad andare via perch\u00e9 la bimba, anche se dormiva, avrebbe potuto disturbare<\/p>\n","protected":false},"author":22,"featured_media":99659,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[7],"tags":[],"class_list":["post-99658","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-universita"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/99658","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=99658"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/99658\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/99659"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=99658"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=99658"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=99658"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}