{"id":99753,"date":"2018-10-15T16:59:29","date_gmt":"2018-10-15T14:59:29","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/abuso-alcol-tra-minori-cosenza-al-secondo-posto-per-tasso-di-mortalita\/"},"modified":"2023-01-16T19:00:57","modified_gmt":"2023-01-16T18:00:57","slug":"259660-abuso-alcol-tra-minori-cosenza-al-secondo-posto-per-tasso-di-mortalita","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/259660-abuso-alcol-tra-minori-cosenza-al-secondo-posto-per-tasso-di-mortalita\/","title":{"rendered":"Abuso alcol tra minori: Cosenza al secondo posto per tasso di mortalit\u00e0"},"content":{"rendered":"<h4>In Italia la Calabria sale sul podio conquistando un terzo posto\u00a0per tasso di mortalit\u00e0 per patologie totalmente alcol-attribuibili<\/h4>\n<p><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-259665 alignleft\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2018\/10\/commissione-sanit\u00e0-audizione-maria-francesca-amendola-373x280.jpg\" alt=\"\" width=\"373\" height=\"280\" title=\"\">COSENZA &#8211; La commissione consiliare sanit\u00e0 di Palazzo dei Bruzi, presieduta dalla consigliera comunale Maria Teresa De Marco, ha ospitato, nel pomeriggio di oggi, l&#8217;audizione della dottoressa Maria Francesca Amendola, responsabile del servizio alcologia dell&#8217;ASP di Cosenza. Al centro dell&#8217;incontro, la discussione, sollevata nei giorni scorsi dalla consigliera comunale Bianca Rende, sulla diffusione in citt\u00e0 del fenomeno dell&#8217;abuso di alcol da parte degli adolescenti. Dopo l&#8217;introduzione della Presidente di Commissione De Marco, la dottoressa Amendola ha illustrato alcuni dati tratti dal rapporto epidemiologico Alcol-correlato, commissionato dalla Regione Calabria all&#8217;Istituto Superiore di Sanit\u00e0 e relativo all&#8217;anno 2017.<\/p>\n<p>\u201cL&#8217;abuso di alcol tra i minori \u2013 ha sottolineato la dottoressa Amendola \u2013 \u00e8 diventato un vero e proprio allarme sociale. La Calabria figura al terzo posto in Italia per tasso di mortalit\u00e0 per patologie totalmente alcol-attribuibili e la provincia di Cosenza \u00e8 al secondo posto dopo Catanzaro. \u201cPer i ragazzi minorenni \u2013 ha detto durante la sua audizione Maria Francesca Amendola &#8211; qualsiasi tipo di consumo, anche occasionale, \u00e8 da considerare a rischio e la legge vieta la vendita e somministrazione di qualsiasi tipo e quantitativo di bevanda alcolica\u201d.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-259663 alignright\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2018\/10\/commissione-sanit\u00e0-audizione-maria-francesca-amendola-4-373x280.jpg\" alt=\"\" width=\"373\" height=\"280\" title=\"\">La responsabile del servizio Alcologia dell&#8217;Asp ha, inoltre, fatto riferimento al cos\u00ecddetto binge drinking, una modalit\u00e0 di consumo di alcol particolarmente sviluppato tra i giovani e che si sta facendo strada anche da noi e che consiste in quel consumo eccessivo episodico, concentrato in un arco ristretto di tempo, di bevande alcoliche di qualsiasi tipo, in modo consecutivo. In una situazione del genere, il suggerimento arrivato dalla dottoressa Amendola alla Commissione sanit\u00e0 e al Comune \u00e8 stato chiaro: \u201coccorre far rispettare la legge ed il divieto di vendita e di somministrazione di bevande alcoliche nei locali, nei supermercati, in tutti quei luoghi dove l&#8217;adolescente pu\u00f2 essere a rischio consumo\u201d. Ci\u00f2 che ha suggerito Maria Francesca Amendola all&#8217;Amministrazione comunale\u00a0 \u00e8 \u201coperare una scelta di campo, facendo rispettare le norme, anche con ordinanze apposite che ricordino le norme vigenti, con l&#8217;affissione nei locali pubblici di una cartellonistica appropriata ed intensificando i controlli della Polizia Municipale. Oggi chi \u00e8 genitore \u2013 ha detto ancora la dottoressa Amendola \u2013 deve ammettere, suo malgrado, che i figli non riconoscono le loro passioni e che hanno stili di vita completamente diversi rispetto ai nostri. Complicato diventa anche fare prevenzione nelle scuole se non si \u00e8 preparati ed in condizione di riconoscere il linguaggio dei ragazzi\u201d.<\/p>\n<p>Nel corso della seduta di commissione \u00e8 intervenuta la Presidente Maria Teresa De Marco che, oltre a sottolineare la portata allarmante del fenomeno, ha evidenziato la diminuzione, negli ultimi dieci anni, in Calabria, di ben il 75% dei CAT (Club Alcologici Territoriali) e l&#8217;aumento di consumo di bevande alcoliche nelle donne, direttamente correlato al grado di scolarizzazione. Nel dibattito sono poi intervenuti, i consiglieri comunali Damiano Covelli, Bianca Rende, Annalisa Apicella e Gisberto Spadafora.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-259662 alignleft\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2018\/10\/commissione-sanit\u00e0-audizione-maria-francesca-amendola-3-373x280.jpg\" alt=\"\" width=\"373\" height=\"280\" title=\"\">Covelli ha avanzato al Comune la proposta di rendersi parte attiva per far rispettare il divieto assoluto di vendita e somministrazione di bevande alcoliche e di insediare un tavolo istituzionale permanente, con la partecipazione dei rappresentanti di Asp, Prefettura, Questura e Confcommercio, con il compito precipuo di vigilare sul rispetto delle prescrizioni di legge, favorendo nel contempo anche un cambio culturale e di mentalit\u00e0. Per Bianca Rende \u201cl&#8217;abuso di alcol tra gli adolescenti \u00e8 uno degli aspetti pi\u00f9 preoccupanti che investe la nostra citt\u00e0 a 360 gradi, interessando tutte le fasce sociali. Proviamo a mettere in campo delle strategie efficaci che siano d&#8217;aiuto anche alle famiglie ed alla scuola che non sempre riesce a fronteggiare tutto\u201d. Anche Bianca Rende si \u00e8 dichiarata d&#8217;accordo con l&#8217;insediamento di un tavolo permanente, favorendo il confronto con il mondo della scuola \u201cper motivare i ragazzi a scelte di vita pi\u00f9 sane e pi\u00f9 consapevoli\u201d. Favorevole al tavolo interistituzionale anche Annalisa Apicella che ha sottolineato la gravit\u00e0 del fenomeno e la necessit\u00e0 per l&#8217;Amministrazione comunale di un&#8217;assunzione di responsabilit\u00e0, intensificando i controlli a campione negli esercizi commerciali per far rispettare le norme vigenti. Della necessit\u00e0 di procedere a controlli da parte della Polizia Municipale, ha, infine, parlato anche il consigliere Gisberto Spadafora. La riunione \u00e8 stata aggiornata ad una prossima seduta nel corso della quale la responsabile del servizio di alcologia dell&#8217;Asp presenter\u00e0 una proposta progettuale sull&#8217;argomento.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>In Italia la Calabria sale sul podio conquistando un terzo posto\u00a0per tasso di mortalit\u00e0 per patologie totalmente alcol-attribuibili<\/p>\n","protected":false},"author":37,"featured_media":99754,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[42],"tags":[],"class_list":["post-99753","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cosenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/99753","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/37"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=99753"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/99753\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/99754"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=99753"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=99753"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=99753"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}