{"id":9986,"date":"2012-12-19T13:38:07","date_gmt":"2012-12-19T12:38:07","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=9986"},"modified":"2023-01-17T13:43:07","modified_gmt":"2023-01-17T12:43:07","slug":"4464-ance-il-crotonese-chisari-commissario-garanzia-giovani","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/4464-ance-il-crotonese-chisari-commissario-garanzia-giovani\/","title":{"rendered":"Ance: il crotonese Chisari Commissario garanzia giovani"},"content":{"rendered":"<p><strong>CROTONE<\/strong>, 19 dic. &#8211; Giuseppe Chisari, Presidente del gruppo Giovani di Ance (associazione nazionale costruttori) Crotone, e&#8217; stato chiamato all&#8217;unanimita&#8217; dal Consiglio Centrale dei<\/p>\n<p>  <!--more-->  <\/p>\n<p>Giovani Ance a ricoprire per il triennio 2012\/2015 l&#8217;importante incarico di Commissario di Garanzia in seno al massimo organo deliberativo di Ance giovani nazionale. &#8220;Chisari, Amministratore dell&#8217;impresa Gaetano Chisari srl di Isola Capo Rizzuto, &#8211; spiega un comunicato &#8211; e&#8217; il primo calabrese ad essere nominato nella Commissione di Garanzia nazionale che, composta da soli tre membri, ha il delicato compito di verificare contenuti ed applicazione degli statuti dei gruppi provinciali e regionali nonche&#8217; di controllare il possesso dei requisiti dei componenti i Consigli Nazionale e Centrale&#8221;.<\/p>\n<p>Fonte AGI<\/p>\n","protected":false},"excerpt":{"rendered":"<p>CROTONE, 19 dic. &#8211; Giuseppe Chisari, Presidente del gruppo Giovani di Ance (associazione nazionale costruttori) Crotone, e&#8217; stato chiamato all&#8217;unanimita&#8217; dal Consiglio Centrale dei<\/p>\n","protected":false},"author":22,"featured_media":9987,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,18],"tags":[],"class_list":["post-9986","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-dai-comuni"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/9986","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=9986"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/9986\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/9987"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=9986"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=9986"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=9986"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}