{"id":99878,"date":"2018-10-18T16:57:57","date_gmt":"2018-10-18T14:57:57","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/cosenza-censimento-permanente-della-popolazione\/"},"modified":"2023-01-16T19:01:05","modified_gmt":"2023-01-16T18:01:05","slug":"260031-cosenza-censimento-permanente-della-popolazione","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/260031-cosenza-censimento-permanente-della-popolazione\/","title":{"rendered":"Cosenza, censimento permanente della popolazione"},"content":{"rendered":"<h4><strong>La Prefettura di Cosenza e l\u2019Istat uniti nelle attivit\u00e0 per le operazioni del Censimento Permanente della Popolazione e delle Abitazioni<\/strong><\/h4>\n<p><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p>COSENZA &#8211; Anche nella provincia di Cosenza la\u00a0 prima domenica di ottobre del 2018 \u00e8 stata la data che ha sancito ufficialmente l\u2019avvio in cinquanta Comuni delle operazioni del Censimento Permanente della Popolazione e delle Abitazioni effettuato dall&#8217;Istituto Nazionale di Statistica (Istat) in perfetta sinergia e collaborazione con l\u2019Ufficio Provinciale del Censimento della Prefettura di Cosenza all\u2019uopo costituito.<\/p>\n<p>L\u2019Ufficio Territoriale del Governo, infatti, oltre ad aver collaborato nella fase della formazione dei responsabili e dei coordinatori delle attivit\u00e0 di rilevazione, \u00e8 coinvolto, \u00a0unitamente ai Responsabili territoriali dell&#8217;Istat, \u00a0nel coordinamento e nella vigilanza sul corretto svolgimento delle operazioni, e nel fornire supporto ai comuni. Il nuovo censimento \u00e8 in grado di restituire, spiega l&#8217;Istat, informazioni rappresentative di tutta la popolazione grazie all\u2019integrazione dei dati raccolti con le diverse rilevazioni (areale e da lista) con quelli provenienti dalle fonti amministrative, cio\u00e8 in possesso delle amministrazioni pubbliche.<\/p>\n<p>A differenza dei censimenti decennali quelli permanenti non coinvolgono tutti i cittadini, le imprese e le istituzioni, ma di volta in volta campioni rappresentativi di essi, restituendo tuttavia dati riferibili al campo di osservazione complessivo, anche grazie all&#8217;integrazione con fonti amministrative.<strong>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/strong><\/p>\n<p>L&#8217;obiettivo \u00e8 aumentare quantit\u00e0 e qualit\u00e0 dell&#8217;offerta informativa sulle caratteristiche della popolazione e sulla tipologia delle abitazioni a livello nazionale, provinciale e locale, e determinare la popolazione legale di ogni comune. Il nuovo approccio all&#8217;informazione statistica, fornendo la base per analisi sulle caratteristiche dei territori, favorir\u00e0 anche lo sviluppo di politiche &#8220;data driven&#8221;, cio\u00e8 guidate dai dati, e la creazione di reti e di processi di innovazione.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Prefettura di Cosenza e l\u2019Istat uniti nelle attivit\u00e0 per le operazioni del Censimento Permanente della Popolazione e delle Abitazioni<\/p>\n","protected":false},"author":37,"featured_media":99879,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[42,1],"tags":[],"class_list":["post-99878","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cosenza","category-senza-categoria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/99878","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/37"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=99878"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/99878\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/99879"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=99878"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=99878"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=99878"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}